{"id":44686,"date":"2024-06-10T11:17:09","date_gmt":"2024-05-08T13:19:32","guid":{"rendered":"https:\/\/ismartgate.com\/automatic-technology-nes-24v2-neoslider-instruction-manual\/"},"modified":"2024-06-10T11:17:09","modified_gmt":"2024-06-10T10:17:09","slug":"manuale-distruzione-della-tecnologia-automatica-nes-24v2-neoslider","status":"publish","type":"page","link":"https:\/\/ismartgate.com\/it\/automatic-technology-nes-24v2-neoslider-instruction-manual\/","title":{"rendered":"Manuale di istruzioni di Automatic Technology NES-24V2 NeoSlider"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><h1 style=\"text-align: center;\">Manuale di istruzioni di Automatic Technology NES-24V2 NeoSlider<\/h1>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><h2 style=\"text-align: center;\">Manuale di istruzioni per l'apripista Automatic Technology NES-24V2 NeoSlider<\/h2>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><div class=\"fusion-text fusion-text-3\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center;\">L'apriporta FAAC 413 \u00e8 compatibile con l'apriporta FAAC 413. <strong>ismartgate<\/strong> un dispositivo intelligente abilitato al Wi-Fi che migliora le operazioni della porta del garage e del cancello. \u00c8 compatibile con Apple HomeKit, Amazon Alexa, Samsung SmartThings, IFTTT (il 1\u00b0 ottobre 2025 l'integrazione di iSmartGate con IFTTT sar\u00e0 interrotta. Il servizio iSmartGate su IFTTT non sar\u00e0 pi\u00f9 disponibile dopo questa data. Ci scusiamo per gli eventuali disagi che ci\u00f2 potrebbe causare) e Google Home.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:40px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-padding-right:25px;--awb-padding-bottom:0px;--awb-padding-left:25px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4\" style=\"--awb-text-transform:none;\"><h2 class=\"title style-scope ytd-video-primary-info-renderer\" style=\"text-align: center;\">iSG PRO\/LITE\/MINI: installazione su una porta di garage<\/h2>\n<\/div><div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:600px;--awb-max-height:360px;--awb-align-self:center;--awb-width:100%;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:60%;\" ><iframe title=\"Lettore video YouTube 1\" src=\"https:\/\/www.youtube.com\/embed\/UH2cYCycrSE?wmode=transparent&autoplay=0\" width=\"600\" height=\"360\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture;\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-padding-right:25px;--awb-padding-bottom:0px;--awb-padding-left:25px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\" style=\"--awb-text-transform:none;\"><h2 class=\"title style-scope ytd-video-primary-info-renderer\" style=\"text-align: center;\">iSG PRO\/LITE\/MINI: installazione su un cancello<\/h2>\n<\/div><div class=\"fusion-video fusion-youtube\" style=\"--awb-max-width:600px;--awb-max-height:360px;--awb-align-self:center;--awb-width:100%;\"><div class=\"video-shortcode\"><div class=\"fluid-width-video-wrapper\" style=\"padding-top:60%;\" ><iframe title=\"Lettore video YouTube 2\" src=\"https:\/\/www.youtube.com\/embed\/lqEw-Txs70U?wmode=transparent&autoplay=0\" width=\"600\" height=\"360\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture;\"><\/iframe><\/div><\/div><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-right:25px;--awb-padding-bottom:0px;--awb-padding-left:25px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-image-element\" style=\"text-align:center;--awb-max-width:550px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"600\" height=\"482\" alt=\"Confronto tra gli apriporta da garage intelligenti ismartgate: pro, lite e mini. Compatibile con Apple HomeKit, Alexa, Google Assistant, SmartThings, IFTTT\" title=\"Confronto tra gli apriporta da garage intelligenti iSmartgate: pro, lite e mini. Compatibile con Apple HomeKit, Alexa, Google Assistant, SmartThings, IFTTT\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/03\/smart_garage_door_openers_comparision.jpg\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/03\/smart_garage_door_openers_comparision.jpg\" class=\"lazyload img-responsive wp-image-10572\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27600%27%20height%3D%27482%27%20viewBox%3D%270%200%20600%20482%27%3E%3Crect%20width%3D%27600%27%20height%3D%27482%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/03\/smart_garage_door_openers_comparision-200x161.jpg 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/03\/smart_garage_door_openers_comparision-400x321.jpg 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/03\/smart_garage_door_openers_comparision.jpg 600w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 600px\" \/><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:-30px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-size:cover;--awb-margin-bottom:-30px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-6\"><h1 style=\"text-align: center; font-size: 30px;\">Di quale ismartgate ho bisogno?<\/h1>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:640px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"1010\" height=\"470\" title=\"trova_il_tuo_mutuo_mobile\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/find_your_ismartgate_mobile.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/find_your_ismartgate_mobile.png\" alt class=\"lazyload img-responsive wp-image-2258\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271010%27%20height%3D%27470%27%20viewBox%3D%270%200%201010%20470%27%3E%3Crect%20width%3D%271010%27%20height%3D%27470%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/find_your_ismartgate_mobile-200x93.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/find_your_ismartgate_mobile-400x186.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/find_your_ismartgate_mobile-600x279.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/find_your_ismartgate_mobile-800x372.png 800w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/find_your_ismartgate_mobile.png 1010w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 1010px\" \/><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-margin-top:30px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-first\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-size:cover;--awb-margin-bottom:0px;width:25%;width:calc(25% - ( ( 4% + 4% ) * 0.25 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"270\" height=\"244\" alt=\"ragazzo che sta pensando al miglior garage intelligente per la sua casa\" title=\"Qual \u00e8 il miglior garage intelligente per la mia casa?\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/BOY.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/BOY.png\" class=\"lazyload img-responsive wp-image-2267\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27270%27%20height%3D%27244%27%20viewBox%3D%270%200%20270%20244%27%3E%3Crect%20width%3D%27270%27%20height%3D%27244%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/BOY-200x181.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/BOY.png 270w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 270px\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_2 1_2 fusion-one-half\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-size:cover;--awb-margin-bottom:0px;width:50%;width:calc(50% - ( ( 4% + 4% ) * 0.5 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-7\"><h1 style=\"text-align: center; font-size: 48px;\">Di quale ismartgate ho bisogno?<\/h1>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-8\"><p style=\"text-align: center;\">Provate il nostro simulatore e trovate l'ismartgate perfetto per la vostra casa.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-last\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-size:cover;--awb-margin-bottom:0px;width:25%;width:calc(25% - ( ( 4% + 4% ) * 0.25 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><img decoding=\"async\" width=\"270\" height=\"244\" alt=\"ragazza che pensa al miglior garage intelligente per la sua casa\" title=\"Qual \u00e8 il miglior garage intelligente per la mia casa?\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/GIRL.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/GIRL.png\" class=\"lazyload img-responsive wp-image-2268\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27270%27%20height%3D%27244%27%20viewBox%3D%270%200%20270%20244%27%3E%3Crect%20width%3D%27270%27%20height%3D%27244%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/GIRL-200x181.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/11\/GIRL.png 270w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 270px\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-custom-z-index\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-z-index:10;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><input type=\"radio\" style=\"display:none;\" id=\"option-yes\" checked=\"checked\" name=\"option-smart\"\n       class=\"option-smart\" value=\"1\" \/>\n<!------------ ------>\n<div class=\"row row-doors row-green\">\n    <div class=\"col-sm-2 col-xs-2 pd-tb-20\">\n        <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n             src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/garage_icon.png\" alt=\"ismartgate - il miglior apriporta per garage\" \/>\n    <\/div>\n    <div class=\"col-sm-8 col-xs-6 pd-tb-20\">\n        <p><span class=\"fusion-no-small-visibility\">Quanti <\/span>Porte di garage<span\n                class=\"fusion-no-small-visibility\"> avete?<\/span><\/p>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 pd-tb-20\">\n        <select id=\"num_garage_doors\">\n            <option value=\"0\">0<\/option>\n            <option value=\"1\">1<\/option>\n            <option value=\"2\">2<\/option>\n            <option value=\"3\">3<\/option>\n        <\/select>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 line-left\">\n        <i class=\"fa fa-chevron-down\" src=\"\" id=\"collapse-block-green\"><\/i>\n    <\/div>\n<\/div>\n<div class=\"block-green row\">\n    <div class=\"col-xs-12\">\n        <div class=\"row\">\n            <!-- modelos de puertas -->\n            <div id=\"garage-1\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/garage_sectional.png\"\n                         class=\"lazyload img-center img-responsive\" alt=\"apriporta sezionale per garage\"\/>\n                <\/div>\n                <p class=\"door-title\">PORTA 1 TIPO:<\/p>\n                <p class=\"door-model\" id=\"garage-door-model-1\">Sezionale<\/p>\n                <p class=\"door-model-description\" id=\"garage-door-model-description-1\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-type-garage\" data-number=\"1\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-type-garage\" data-number=\"1\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"garage-1-selected\" value=\"1\" \/>\n            <\/div>\n            <div id=\"garage-2\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/garage_sectional.png\"\n                         class=\"lazyload img-center img-responsive\" alt=\"apriporta sezionale per garage\"\/>\n                <\/div>\n                <p class=\"door-title\">PORTA 2 TIPO:<\/p>\n                <p class=\"door-model\" id=\"garage-door-model-2\">Sezionale<\/p>\n                <p class=\"door-model-description\" id=\"garage-door-model-description-2\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-type-garage\" data-number=\"2\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-type-garage\" data-number=\"2\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"garage-2-selected\" value=\"1\" \/>\n            <\/div>\n            <div id=\"garage-3\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/garage_sectional.png\"\n                         class=\"lazyload img-center img-responsive\" alt=\"apriporta sezionale per garage\"\/>\n                <\/div>\n                <p class=\"door-title\">PORTA 3 TIPO:<\/p>\n                <p class=\"door-model\" id=\"garage-door-model-3\">Sezionale<\/p>\n                <p class=\"door-model-description\" id=\"garage-door-model-description-3\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-type-garage\" data-number=\"3\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-type-garage\" data-number=\"3\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"garage-3-selected\" value=\"1\" \/>\n            <\/div>\n        <\/div>\n\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"garage-sensor-type\">\n                <!-- separacion -->\n                <p class=\"title-section\">Tipo di sensore<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/img-sensor-type.png\" alt=\"Simulatore di porta di garage ismartgate, tipo sensore\"\n                         id=\"img-sensor-type-garage\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete uno o pi\u00f9 sensori wireless o cablati per la\/e porta\/e del garage? <\/p>\n                <p class=\"descrip-section\"><\/p>\n                <select class=\"sel-separation\" id=\"sensor-type-garage\">\n                    <option value=\"0\">Sensore wireless<\/option>\n                    <option value=\"1\">Sensore cablato<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"garage-security\">\n                <!-- video -->\n                <p class=\"title-section\">Il vostro apriporta \u00e8 Chamberlain, Liftmaster o Craftsman?<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/security.png\" alt=\"Simulatore di porta di garage ismartgate, sicurezza\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Avete un apriporta di garage Chamberlain o LiftMaster con Security+2.0?<\/p>\n                <p class=\"descrip-section\">Controllate il colore del pulsante di apprendimento sul vostro apri garage. Se \u00e8 giallo, il vostro apriporta utilizza il sistema Security+2.0 e avrete bisogno dell'adattatore per interruttori ismartgate.<\/p>\n                <form action=\"\">\n                    <div class=\"row\" style=\"max-width: 420px;margin: auto;\">\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-security-1\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 1<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-security-2\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 2<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-security-3\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 3<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n            <\/div>\n        <\/div>\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"garage-separation\">\n                <!-- separacion -->\n                <p class=\"title-section\">Separazione<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/garage_separation.gif\" alt=\"Simulatore di porta di garage ismartgate, 3 porte separate\"\n                         id=\"img-separation-garage\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Le porte del garage sono collegate? <i\n                        onclick=\"ShowModalProd('\/images\/simulator\/separation.gif','Separation','')\"\n                        class=\"grey-icon fa fa-question-circle-o\"><\/i><\/p>\n                <p class=\"descrip-section\">Se i garage non hanno pareti di separazione sono considerati\n                    \"collegato\"<\/p>\n                <select class=\"sel-separation\" id=\"number-separation-garage\">\n                    <option value=\"0\">S\u00ec<\/option>\n                    <option value=\"1\">1 Separazione<\/option>\n                    <option value=\"2\" id=\"garage-sep-2-option\">2 Separazioni<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"garage-video\">\n                <!-- video -->\n                <p class=\"title-section\">Video in diretta<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/video.png\" alt=\"simulatore di porta di garage ismartgate, video\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete vedere cosa succede nel vostro garage in tempo reale?<\/p>\n                <p class=\"descrip-section\">Controllate le porte del garage con un video in diretta nell'app<\/p>\n                <form action=\"\">\n                    <div class=\"row\" style=\"max-width: 420px;margin: auto;\">\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-cam-1\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 1<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-cam-2\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 2<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-cam-3\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 3<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n<\/div>\n<!------------ ------>\n<div class=\"row row-doors row-blue\">\n    <div class=\"col-sm-2 col-xs-2 pd-tb-20\">\n        <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n             src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/gate_icon.png\" alt=\"apricancello ismartgate con telecamera\" \/>\n    <\/div>\n    <div class=\"col-sm-8 col-xs-6 pd-tb-20\">\n        <p><span class=\"fusion-no-small-visibility\">Quanti <\/span>Cancelli<span\n                class=\"fusion-no-small-visibility\"> avete?<\/span><\/p>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2  pd-tb-20\">\n        <select id=\"num_gate_doors\">\n            <option value=\"0\">0<\/option>\n            <option value=\"1\">1<\/option>\n            <option value=\"2\">2<\/option>\n            <option value=\"3\">3<\/option>\n        <\/select>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 line-left\">\n        <i class=\"fa fa-chevron-down\" src=\"\" id=\"collapse-block-blue\"><\/i>\n    <\/div>\n<\/div>\n<div class=\"block-blue row\">\n    <div class=\"col-xs-12\">\n        <div class=\"row\">\n            <!-- modelos de puertas -->\n            <div id=\"gate-1\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/gate_sliding.png\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"door-title\">PORTA 1 TIPO:<\/p>\n                <p class=\"door-model\" id=\"gate-door-model-1\">Cancello scorrevole<\/p>\n                <p class=\"door-model-description\" id=\"gate-door-model-description-1\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-gate\" data-number=\"1\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-gate\" data-number=\"1\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"gate-1-selected\" value=\"6\" \/>\n            <\/div>\n            <div id=\"gate-2\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/gate_sliding.png\" alt=\"simulatore ismartgate - cancello scorrevole\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"door-title\">PORTA 2 TIPO:<\/p>\n                <p class=\"door-model\" id=\"gate-door-model-2\">Cancello scorrevole<\/p>\n                <p class=\"door-model-description\" id=\"gate-door-model-description-2\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-gate\" data-number=\"2\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-gate\" data-number=\"2\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"gate-2-selected\" value=\"6\" \/>\n            <\/div>\n            <div id=\"gate-3\" class=\"col-sm-4 col-xs-12\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/gate_sliding.png\" alt=\"simulatore ismartgate - cancello scorrevole\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"door-title\">PORTA 3 TIPO:<\/p>\n                <p class=\"door-model\" id=\"gate-door-model-3\">Cancello scorrevole<\/p>\n                <p class=\"door-model-description\" id=\"gate-door-model-description-3\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-gate\" data-number=\"3\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-gate\" data-number=\"3\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"gate-3-selected\" value=\"6\" \/>\n            <\/div>\n        <\/div>\n\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"gate-sensor-type\">\n                <!-- separacion -->\n                <p class=\"title-section\">Tipo di sensore<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/img-sensor-type.png\" alt=\"Porta di simulazione ismartgate, tipo sensore\"\n                         id=\"img-sensor-type-gate\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete uno o pi\u00f9 sensori wireless o cablati per la\/e porta\/e del garage? <\/p>\n                <p class=\"descrip-section\"><\/p>\n                <select class=\"sel-separation\" id=\"sensor-type-gate\">\n                    <option value=\"0\">Sensore wireless<\/option>\n                    <option value=\"1\">Sensore cablato<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"gate-power\">\n                <!-- separacion -->\n                <p class=\"title-section\">Presa di corrente per cancello<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/img-power-outlet.png\" alt=\"Cancello di simulazione ismartgate, presa di alimentazione\"\n                         id=\"img-power-outlet-gate\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Avete una presa da 110V\/220V vicino al vostro cancello?<\/p>\n                <p class=\"descrip-section\">Se non si dispone di una presa di corrente da 110V\/220V vicino al cancello, \u00e8 necessario un convertitore di corrente DC\/DC per alimentare l'apriporta ismartgate.<\/p>\n                <select class=\"sel-separation\" id=\"power-outlet-gate\">\n                    <option value=\"0\">S\u00ec<\/option>\n                    <option value=\"1\">No<\/option>\n                <\/select>\n            <\/div>\n        <\/div>\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"gate-separation\">\n                <!-- separacion -->\n                <p class=\"title-section\">Separazione<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/gate_separation_3_doors.png\" alt=\"simulatore di cancello ismartgate separazione 3 porte\"\n                         id=\"img-separation-gate\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">I vostri cancelli sono collegati?<\/p>\n                <p class=\"descrip-section\">Meno di 30 piedi sono considerati \"collegati\"<\/p>\n                <select class=\"sel-separation\" id=\"number-separation-gate\">\n                    <option value=\"0\">S\u00ec<\/option>\n                    <option value=\"1\">1 Separazione<\/option>\n                    <option value=\"2\" id=\"gate-sep-2-option\">2 Separazioni<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"gate-video\">\n                <!-- video -->\n                <p class=\"title-section\">Video in diretta<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/video.png\" alt=\"simulatore di porta di garage ismartgate, video\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete vedere cosa succede nel vostro gate in tempo reale?<\/p>\n                <p class=\"descrip-section\">Controllo dei cancelli con video in diretta nell'app<\/p>\n                <form action=\"\">\n                    <div class=\"row\" style=\"max-width: 420px;margin: auto;\">\n                        <div class=\"col-sm-4 col-xs-4\" id=\"gate-cam-1\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 1<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"gate-cam-2\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 2<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"gate-cam-3\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 3<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<!------------ ------>\n<div class=\"row row-doors row-red\">\n    <div class=\"col-sm-2 col-xs-2 pd-tb-20\">\n        <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n             style=\"width:52px;\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Icon_smarthomes.png\" alt=\"SmartHome\" \/>\n    <\/div>\n    <div class=\"col-sm-8 col-xs-8 pd-tb-20 smarthome-title\">\n        <p>Voglio che ismartgate sia compatibile con: <br \/>\n            <img decoding=\"async\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/click_to_select_deselect.gif\" alt=\"Fare clic per selezionare\/deselezionare l&#039;opzione di compatibilit\u00e0 dell&#039;apriporta del garage intelligente ismartgate con\" \/><\/p>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 hidden-xs pd-tb-20\">\n\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 line-left\">\n        <i class=\"fa fa-chevron-up\" id=\"collapse-block-red\"><\/i>\n    <\/div>\n<\/div>\n<div class=\"block-red row\">\n    <div class=\"col-xs-6\">\n        <div class=\"row\">\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-Apple\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Apple_OFF.png\" alt=\"Apple Homekit compatibile con l&#039;apriporta del garage ismartgate\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"apple-homekit-option\" name=\"apple-homekit-option\" data-img=\"Apple\" value=\"0\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-Alexa\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Alexa_ON.png\" alt=\"Apriporta da garage intelligente compatibile con Amazon Alexa\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"alexa-option\" name=\"alexa-option\" checked=\"checked\" data-img=\"Alexa\" value=\"1\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-Google\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Google_ON.png\" alt=\"Apriporta da garage compatibile con l&#039;assistente Google\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"google-option\" name=\"google-option\" checked=\"checked\" data-img=\"Google\" value=\"1\" \/>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"col-xs-6\">\n        <div class=\"row\">\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-SmartThings\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/SmartThings_OFF.png\" alt=\"Apriporta di garage intelligente compatibile con SmartThings\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"smartthings-option\" name=\"smartthings-option\" data-img=\"SmartThings\" value=\"0\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\" style=\"display: none\">\n                <img decoding=\"async\" id=\"imgoption-IFTTT\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/IFTTT_ON.png\" alt=\"Apriporta da garage intelligente compatibile con IFTTT\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"ifttt-option\" name=\"ifttt-option\" checked=\"checked\" data-img=\"IFTTT\" value=\"0\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\" style=\"display: none\">\n                <img decoding=\"async\" id=\"imgoption-none\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/none_OFF.png\" alt=\"Nessuno (non \u00e8 stata selezionata la compatibilit\u00e0 con Alexa, Apple HomeKit, Google assistant, SmartThings o IFTTT)\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"none-option\" name=\"none-option\" data-img=\"none\" value=\"0\" \/>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!------------ ------>\n\n<h6 class=\"text-center\">Se la vostra casa non corrisponde a queste opzioni, inviateci un'e-mail a <a\n        href=\"mailto:support@ismartgate.com\">support@ismartgate.com<\/a><\/h6>\n<br \/>\n<br \/><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat button-medium button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#ffffff;--button_border_width-top:1px;--button_border_width-right:1px;--button_border_width-bottom:1px;--button_border_width-left:1px;--button_gradient_top_color:#0d89cc;--button_gradient_bottom_color:#0d89cc;--button_gradient_top_color_hover:#0a0303;--button_gradient_bottom_color_hover:#0a0303;\" target=\"_self\" id=\"btn_get_result\"><i class=\"fa-chevron-down fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Ottenere il risultato<\/span><\/a><\/div><div id=\"result-simulator\">\n                <div class=\"row row-white\">\n                    <div class=\"col-xs-12\">\n                        <p class=\"title-result\">RISULTATO FINALE<\/p>\n                    <\/div>\n                    <br \/>\n                    <div class=\"col-sm-12\" id=\"block-result-smart\">\n                        <div class=\"row\">\n                            <div class=\"col-sm-2 icon-door\">\n                                <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n                        style=\"width:52px;\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Icon_smarthomes.png\" alt=\"SmartHome\" \/>\n                            <\/div>\n                            <div class=\"col-sm-8 col-xs-12\">\n                                <div class=\"block-buy-center block-smart\">\n                                    <p class=\"title-section option-1-res\">Apriscatole Compatibile con: \n                                        <div class=\"block-res-img\">\n                                            <img decoding=\"async\" id=\"res-smart-img-apple-homekit\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Apple_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-alexa\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Alexa_ON.png\" alt=\"Alexa\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-google\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Google_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-smartthings\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/SmartThings_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-ifttt\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/IFTTT_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-none\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/none_ON.png\" alt=\"Alexa\" \/>\n                                        <\/div>\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-2 icon-door\"><\/div>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-sm-6 line-right\" id=\"block-result-garage\">\n                        <div class=\"row header-result\">\n                            <div class=\"col-sm-4 icon-door\">\n                                <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n                                    src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/garage_icon.png\" alt=\"ismartgate - il miglior apriporta per garage\"\/>\n                            <\/div>\n                            <div class=\"col-sm-8\">\n                                <div class=\"block-buy-center\">\n                                    <p class=\"title-result-section\">La vostra selezione per <span id=\"res_number_garage\">0<\/span>x GARAGE\n                                        PORTA<span id=\"res_s_garage\">S<\/span>:<\/p>\n                                    <p class=\"result-content\">\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"row line-bottom-xs\">\n                            <div class=\"col-sm-8 col-sm-offset-4 buy-result\">\n                                <div class=\"block-buy-center\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-sm-6\" id=\"block-result-gate\">\n                        <div class=\"row header-result\">\n                            <div class=\"col-sm-8\">\n                                <div class=\"block-buy-center\">\n                                    <p class=\"title-result-section\">La vostra selezione per <span id=\"res_number_gate\">0<\/span>x GATE<span\n                                            id=\"res_s_gate\">S<\/span>:<\/p>\n                                    <p class=\"result-content\">\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-4 icon-door\">\n                                <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n                                    src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/gate_icon.png\" \/>\n                            <\/div>\n                        <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-sm-8 buy-result\">\n                                <div class=\"block-buy-center\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n        <div class=\"row row-grey\">\n            <p class=\"title-result\">COMPRARE TUTTO ORA:<\/p>\n            <p class=\"block-buttons buttons-isg\">\n              <a class=\"button-flat fusion-button-pill button-large button-default button-1\" href=\"\/it\/acquistare-un-garage-intelligente\/\" target=\"_blank\"><i class=\"fa-shopping-cart fas button-icon-left\"><\/i><span class=\"fusion-button-text\">ACQUISTA ORA<\/span><\/a>\n          <\/p>\n        <\/div>\n    <\/div><div id=\"overlay-buy\" style=\"display:none;\" onclick=\"HideModal()\"><\/div>\n<div id=\"block-buy\" style=\"display:none;\">\n    <span onclick=\"HideModal()\" id=\"close-modal-sim\" style=\"cursor:pointer;margin-top:-3px;margin-right:-3px;height: 20px !important;overflow: hidden;display: inherit;\">\n        <i style=\"font-size:20px;\" class=\"pull-right fa fa-close\"><\/i><\/span>\n        <h5><\/h5>\n        <p class=\"result-content\" style=\"margin-bottom:0;margin-top:0;\"><\/p>\n        <hr style=\"border: 1px solid #eee;margin-top:10px;margin-bottom:10px;\">\n        <img decoding=\"async\" class=\"lazyload img-center img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\">\n<\/div>\n\n<link rel='stylesheet' id='cfaq-adminGlobal-css'  href='\/css\/simulator_4.css?v=1.1' type='text\/css' \/>\n<script src=\"https:\/\/code.jquery.com\/jquery-3.3.1.min.js\"\n\t\t\t  integrity=\"sha256-FgpCb\/KJQlLNfOu91ta32o\/NMZxltwRo8QtmkMRdAu8=\"\n\t\t\t  crossorigin=\"anonymous\"><\/script>\n<script type='text\/javascript'>\n\tjq_ggg = jQuery.noConflict( true );\n<\/script>\n<script type='text\/javascript' src='\/js\/simulator_4.js?v=1.2'><\/script><div class=\"fusion-clearfix\"><\/div><\/div><\/div>\n<\/div><\/div>\n<section class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:1px;--awb-background-color:#f7f7f7;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:30px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-9\" style=\"--awb-text-transform:none;\"><h2 style=\"color: #ffffff; font-size: 23pt; letter-spacing: -1px; text-align: center; line-height: normal;\"><span style=\"color: #000000;\">Cosa pu\u00f2 fare l'apriporta del garage ismartgate?<\/span><\/h2>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-top:25px;margin-bottom:40px;width:100%;max-width:15%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#000000;border-color:#000000;border-top-width:5px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img decoding=\"async\" width=\"841\" height=\"538\" title=\"apertura_garage_per_android_auto\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/smart_garage_opener_for_android_auto.jpg\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/smart_garage_opener_for_android_auto.jpg\" alt class=\"lazyload img-responsive wp-image-20530\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27841%27%20height%3D%27538%27%20viewBox%3D%270%200%20841%20538%27%3E%3Crect%20width%3D%27841%27%20height%3D%27538%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/smart_garage_opener_for_android_auto-200x128.jpg 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/smart_garage_opener_for_android_auto-400x256.jpg 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/smart_garage_opener_for_android_auto-600x384.jpg 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/smart_garage_opener_for_android_auto-800x512.jpg 800w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/smart_garage_opener_for_android_auto.jpg 841w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 841px\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/section>\n<section class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:20px;--awb-padding-right:0px;--awb-padding-bottom:20px;--awb-padding-left:1px;--awb-background-color:#5567aa;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><ul style=\"--awb-item-padding-right:5%;--awb-item-padding-left:5%;--awb-textcolor:#ffffff;--awb-line-height:23.8px;--awb-icon-width:23.8px;--awb-icon-height:23.8px;--awb-icon-margin:9.8px;--awb-content-margin:33.6px;--awb-circlecolor:#a0ce4e;--awb-circle-yes-font-size:12.32px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons older-models-checklist-2\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Utilizzate il vostro smartphone per controllare a distanza la porta del garage o il cancello tramite Wi-Fi o Internet.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Controllate la porta del garage o il cancello con un video in tempo reale.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Controllare se la porta o il cancello del garage sono aperti o chiusi.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Utilizzate Apple HomeKit, Amazon Alexa, Google Home, IFTTT o Samsung SmartThings per azionare la porta o il cancello del garage.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Controllare chi ha aperto o chiuso la porta o il cancello del garage.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Utilizzate il vostro Apple Watch e le scorciatoie di Siri per azionare la porta o il cancello del garage.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Gestite l'accesso alla porta del garage o al cancello da remoto per utente, orario, porta e anche per localit\u00e0.<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Aprire automaticamente la porta del garage o il cancello quando si arriva a casa (geofencing).<\/div><\/li><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-yes\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">Programmate quando la porta del garage o il cancello devono aprirsi e chiudersi automaticamente.<\/div><\/li><\/ul><style>\n.older-models-checklist-2 li div {font-size:18px;}\n<\/style><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/section>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:30px;--awb-background-color:#ffffff;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-no-small-visibility fusion-column-inner-bg-wrapper\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-inner-bg-position:center center;--awb-inner-bg-size:cover;--awb-border-color:#b7b7b7;--awb-border-top:0;--awb-border-style:solid;--awb-margin-bottom:0px;\"><span class=\"fusion-column-inner-bg hover-type-none\"><a class=\"fusion-column-anchor\" href=\"\/it\/acquistare-un-garage-intelligente\/\"><span class=\"fusion-column-inner-bg-image lazyload\" data-bg=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2024\/10\/1n2-80-1.jpg\"><\/span><\/a><\/span><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2024\/10\/1n2-80-1.jpg\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:25px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-no-medium-visibility fusion-no-large-visibility fusion-column-inner-bg-wrapper\" style=\"--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-inner-bg-size:cover;--awb-border-color:#b7b7b7;--awb-border-top:0;--awb-border-style:solid;--awb-margin-bottom:0px;\"><span class=\"fusion-column-inner-bg hover-type-none\"><a class=\"fusion-column-anchor\" href=\"\/it\/acquistare-un-garage-intelligente\/\"><span class=\"fusion-column-inner-bg-image lazyload\" data-bg=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2024\/10\/1Banner_mobile-80-1.jpg\"><\/span><\/a><\/span><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy fusion-column-has-bg-image\" data-bg-url=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2024\/10\/1Banner_mobile-80-1.jpg\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-menu-anchor\" id=\"comparision\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:25px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-10\"><h2>Confronta gli apriporta ismartgate<\/h2>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\">\n<table id=\"tablepress-19\" class=\"tablepress tablepress-id-19\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2770%27%20height%3D%2734%27%20viewBox%3D%270%200%2070%2034%27%3E%3Crect%20width%3D%2770%27%20height%3D%2734%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/mini.fw_.png\" alt=\"\" width=\"70\" height=\"34\" class=\"lazyload aligncenter size-full wp-image-17\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2770%27%20height%3D%2734%27%20viewBox%3D%270%200%2070%2034%27%3E%3Crect%20width%3D%2770%27%20height%3D%2734%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismargate_lite_logo.png\" alt=\"\" width=\"70\" height=\"34\" class=\"lazyload aligncenter size-full wp-image-17\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2757%27%20height%3D%2757%27%20viewBox%3D%270%200%2057%2057%27%3E%3Crect%20width%3D%2757%27%20height%3D%2757%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismargate_pro_logo.png\" alt=\"\" width=\"57\" height=\"57\" class=\"lazyload aligncenter size-full wp-image-17\" \/><\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Porte supportate<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">1<\/td><td class=\"column-4\">3<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Avvisi di accesso remoto e di stato della porta<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Apple HomeKit<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Assistente Google<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Samsung SmartThings<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><span style=\"color:red;\">IFTTT***<\/span><\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Amazon Alexa*<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Compatibilit\u00e0 dei sensori wireless<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Compatibilit\u00e0 dei sensori cablati<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Gestione degli utenti<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Integrazione video<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Allarme acustico visivo<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Aprire e chiudere la musica personalizzata<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Compatibilit\u00e0 Wi-Fi (2,4GHz)<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Compatibilit\u00e0 Ethernet**<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Accesso al browser web<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-19 from cache --><div class=\"fusion-text fusion-text-11\" style=\"--awb-text-transform:none;\"><h6>*L'\"abilit\u00e0 ismartgate\" \u00e8 disponibile nelle seguenti lingue: Italiano (IT),Tedesco (DE),Inglese (US),Spagnolo (ES),Spagnolo (US),Francese (FR),Inglese (UK\/IE)<\/h6>\n<\/div><div class=\"fusion-text fusion-text-12\" style=\"--awb-text-transform:none;\"><h6>**<a href=\"https:\/\/ismartgate.com\/it\/accessori-per-garage-intelligenti\/#network\" target=\"_blank\" rel=\"noopener\">Da USB a Ethernet<\/a> per collegare l'iSmartgate al router con un cavo Ethernet.<\/h6>\n<\/div><div class=\"fusion-text fusion-text-13\" style=\"--awb-text-transform:none;\"><h6>***<span data-teams=\"true\">Il 1\u00b0 ottobre 2025<\/span><span data-teams=\"true\">\u00a0l'integrazione di iSmartGate con IFTTT sar\u00e0 interrotta. Il servizio iSmartGate su IFTTT non sar\u00e0 pi\u00f9 disponibile dopo questa data. Ci scusiamo per gli eventuali disagi che ci\u00f2 potrebbe causare.<\/span><\/h6>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:20px;--awb-background-color:#f9f9f9;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-14\" style=\"--awb-text-transform:none;\"><h1 style=\"text-align: center;\">Schemi di cablaggio per il collegamento di ismartgate all'apriporta del garage o del cancello.<\/h1>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-15\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center;\">Controllare il <strong>Istruzioni per il cablaggio<\/strong> per l'installazione dell'apriporta intelligente ismartgate sul vostro apriporta di garage. ismartgate \u00e8 compatibile con tutte le marche di apriporta per garage, compresi gli apriporta Chamberlain, Craftsman e Liftsmaster.<\/p>\n<p style=\"text-align: center;\">Se l'apriporta del vostro garage non \u00e8 presente nell'elenco, inviateci un'e-mail all'indirizzo <strong>support@ismartgate.com<\/strong> indicando la marca e il modello dell'operatore.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:20px;--awb-padding-bottom:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-background-color:#f9f9f9;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_1_6 1_6 fusion-one-sixth fusion-column-first\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:16.666666666667%;width:calc(16.666666666667% - ( ( 4% + 4% + 4% ) * 0.16666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_1_3 1_3 fusion-one-third select-block-buy\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% + 4% + 4% ) * 0.33333333333333 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-16\"><h2 style=\"text-align: center;\">1. Selezionare il produttore:<\/h2>\n<\/div><div class=\"fusion-text fusion-text-17\"><p><select id=\"select-brand\" class=\"select-buy-now col-xs-12\" onchange=\"SelectBrand();return false;\"><option value=\"0\">Seleziona il produttore ...<\/option><\/select><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion_builder_column_1_3 1_3 fusion-one-third select-h2\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% + 4% + 4% ) * 0.33333333333333 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-18\"><h2 style=\"text-align: center;\">2. Selezionare il modello:<\/h2>\n<\/div><div class=\"fusion-text fusion-text-19\"><p><select id=\"select-model\" class=\"select-buy-now col-xs-12\" onchange=\"SelectModel();return false;\"><option value=\"0\">Selezionare il modello ...<\/option><\/select><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion_builder_column_1_6 1_6 fusion-one-sixth fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:16.666666666667%;width:calc(16.666666666667% - ( ( 4% + 4% + 4% ) * 0.16666666666667 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-11 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-6 hover-type-none\"><img decoding=\"async\" width=\"87\" height=\"43\" title=\"separazione_gi\u00f9\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2787%27%20height%3D%2743%27%20viewBox%3D%270%200%2087%2043%27%3E%3Crect%20width%3D%2787%27%20height%3D%2743%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/02\/separation_down.png\" alt class=\"lazyload img-responsive wp-image-769\"\/><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-12 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-22 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-first gate-result-related\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );margin-right: 4%;\" id=\"static-ggg-block\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element in-legacy-container\" style=\"--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-7 hover-type-none img_100_100\"><img decoding=\"async\" width=\"650\" height=\"520\" alt=\"Schema di cablaggio e collegamenti per iSmartgate Lite, Mini, Pro - Aperture per porte e cancelli di garage intelligenti\" title=\"Schema di cablaggio e collegamenti per iSmartgate Lite, Mini, Pro\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update.png\" class=\"lazyload img-responsive wp-image-1951\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27650%27%20height%3D%27520%27%20viewBox%3D%270%200%20650%20520%27%3E%3Crect%20width%3D%27650%27%20height%3D%27520%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update-200x160.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update-400x320.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update-600x480.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update.png 650w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 650px\" \/><\/span><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-23 fusion_builder_column_1_2 1_2 fusion-one-half fusion-column-last gate-result-related\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );\" id=\"gates-block\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><p id=\"brand-label\" class=\"title-buy-now-select\"><\/p>\n<p id=\"model-label\"><\/p>\n<p class=\"static-text\">Controllare l'immagine per vedere le istruzioni su come collegarlo.<\/p>\n<img decoding=\"async\" class=\"lazyload img-center img-responsive\" id=\"brand-model-img\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"https:\/\/gates.gogogate.com\/images\/img_16_LA400-LA400S.jpg\"\/>\n<p style=\"margin-top:25px;\" class=\"title-model-2 model-link-img\">\n\t<a href=\"https:\/\/gates.ismartgate.com\/images\/entrematic\/img_33_LOGIC M (for CUBIC).png\" class=\"link-to-image-model-entrematic title-buy-now-select\" style=\"text-align:center;text-decoration:underline;\"  id=\"link-to-image-model\" target=\"_blank\" download=\"install-guide.jpg\">Salva immagine <i class=\"fa fa-lg fa-download\"><\/i><\/a>\n<\/p><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-24 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"clearfix\"><\/div>\n<div id=\"container-gates\"><\/div>\n\n<div id=\"overlay\" style=\"display:none\"><\/div>\n<div id=\"ball-loading\" style=\"display:none\"><\/div>\n\n<link rel='stylesheet' href='https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/select2\/4.0.5\/css\/select2.min.css' type='text\/css' media='all' \/>\n<script type=\"text\/javascript\" src=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/select2\/4.0.5\/js\/select2.full.min.js\"><\/script>\n\n<script type=\"text\/javascript\" src=\"\/js\/common.js\"><\/script>\n<script type=\"text\/javascript\" src=\"\/js\/gates.js\"><\/script>\n\n\n\n<script type=\"text\/javascript\">\n    function formatState (type) {\n        if ( !(type.id - 0) ) {\n            return type.text;\n        }\n        var baseUrl = \"\/wp-content\/uploads\/type_automations\";\n        var $type = jQuery(\n            '<span class=\"option-type\"><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"' + baseUrl + '\/' + jQuery(type.element).data('image') + '\" \/><span class=\"txt-option\"> ' + type.text + '<\/span><\/span>'\n        );\n        return $type;\n    };\n\n    function formatStateModel (model) {\n        if ( !(model.id) || model.id == \"0\") {\n            return model.text;\n        }\n        var baseUrl = \"\/wp-content\/uploads\/model_automations\";\n        var $model = jQuery(\n            '<span class=\"option-type\"><img class=\"lazyload\" decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"' + baseUrl + '\/' + jQuery(model.element).data('image') + '\" \/><span class=\"txt-option\"> ' + model.text + '<\/span><\/span>'\n        );\n        return $model;\n    };\n    jQuery(\"#id_type_compatibility\").select2({\n        templateResult: formatState,\n        minimumResultsForSearch: -1,\n        templateSelection: formatState\n    }).on('select2:select', function (e) {\n        var type = jQuery(e.params.data.element).data('type');\n        var val = jQuery(e.params.data.element).val();\n        SelectAutomationType(val, type, 1);\n    });\n    InitGateBlock();\n\n\n\n<\/script><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-13 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gate-result-related\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-25 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:10px;--awb-padding-right:10px;--awb-padding-bottom:10px;--awb-padding-left:10px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-border-color:#9e9e9e;--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:dotted;--awb-margin-top:30px;--awb-margin-bottom:30px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-fa-align-center\"><i class=\"fb-icon-element-1 fb-icon-element fontawesome-icon fa-exclamation-triangle fas circle-yes\" style=\"--awb-circlebordersize:1px;--awb-font-size:22px;--awb-width:44px;--awb-height:44px;--awb-line-height:42px;--awb-margin-top:0px;--awb-margin-right:0px;--awb-margin-bottom:-20px;--awb-margin-left:0px;\"><\/i><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-20\"><div class=\"fusion-text\">\n<h2 style=\"text-align: center;\">Se lo schema elettrico indica:<\/h2>\n<\/div>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-no-medium-visibility fusion-no-large-visibility fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_2 1_2 fusion-one-half fusion-column-first\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-8 hover-type-none\"><img decoding=\"async\" width=\"106\" height=\"48\" title=\"opzione_01_isg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27106%27%20height%3D%2748%27%20viewBox%3D%270%200%20106%2048%27%3E%3Crect%20width%3D%27106%27%20height%3D%2748%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/05\/option_01_isg-e1557143099798.png\" alt class=\"lazyload img-responsive wp-image-1498\"\/><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-21\"><p style=\"text-align: center;\"><strong><span style=\"color: #ff0000;\">\u00c8 NECESSARIO:<\/span><\/strong><\/p>\n<\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:200px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-9 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/ismartgate.com\/it\/ismartgate-mini\/\" target=\"_self\" aria-label=\"logo MINI ismartgate\"><img decoding=\"async\" width=\"716\" height=\"105\" alt=\"ismartgate MINI - Apriporta intelligente per cancelli e garage\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/ismartgate_MINI_logo.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/ismartgate_MINI_logo.png\" class=\"lazyload img-responsive wp-image-9475\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27716%27%20height%3D%27105%27%20viewBox%3D%270%200%20716%20105%27%3E%3Crect%20width%3D%27716%27%20height%3D%27105%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/ismartgate_MINI_logo-200x29.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/ismartgate_MINI_logo-400x59.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/ismartgate_MINI_logo-600x88.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/ismartgate_MINI_logo.png 716w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 716px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-22\"><p style=\"text-align: center;\">-- O...<\/p>\n<\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:200px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-10 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/ismartgate.com\/it\/ismartgate-lite\/\" target=\"_self\" aria-label=\"logo ismartgate LITE\"><img decoding=\"async\" width=\"716\" height=\"105\" alt=\"ismartgate LITE - Apriporta intelligente per cancelli e garage\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_LITE_logo.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_LITE_logo.png\" class=\"lazyload img-responsive wp-image-9412\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27716%27%20height%3D%27105%27%20viewBox%3D%270%200%20716%20105%27%3E%3Crect%20width%3D%27716%27%20height%3D%27105%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_LITE_logo-200x29.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_LITE_logo-400x59.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_LITE_logo-600x88.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_LITE_logo.png 716w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 716px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-23\"><p style=\"text-align: center;\">-- O...<\/p>\n<\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:200px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-11 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/ismartgate.com\/it\/ismartgate-pro\/\" target=\"_self\" aria-label=\"logo ismartgate PRO\"><img decoding=\"async\" width=\"677\" height=\"100\" alt=\"ismartgate PRO - Apriporta intelligente per cancelli e garage\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo.png\" class=\"lazyload img-responsive wp-image-9078\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27677%27%20height%3D%27100%27%20viewBox%3D%270%200%20677%20100%27%3E%3Crect%20width%3D%27677%27%20height%3D%27100%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo-200x30.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo-400x59.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo-600x89.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo.png 677w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 677px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:10px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat button-small button-default fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/ismartgate.com\/it\/confronto-tra-gli-apri-garage-intelligenti-ismartgate\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Confronta gli apriporta &gt;<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-no-medium-visibility fusion-no-large-visibility fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:25px;margin-bottom:25px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_2 1_2 fusion-one-half fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:50%;width:calc(50% - ( ( 4% ) * 0.5 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:50%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-12 hover-type-none\"><img decoding=\"async\" width=\"221\" height=\"48\" title=\"opzione_02_isg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27221%27%20height%3D%2748%27%20viewBox%3D%270%200%20221%2048%27%3E%3Crect%20width%3D%27221%27%20height%3D%2748%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/05\/option_02_isg-e1557143113620.png\" alt class=\"lazyload img-responsive wp-image-1500\"\/><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-24\"><p style=\"text-align: center;\"><strong><span style=\"color: #ff0000;\">\u00c8 NECESSARIO:<\/span><\/strong><\/p>\n<\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:200px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-13 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/ismartgate.com\/it\/ismartgate-pro\/\" target=\"_self\" aria-label=\"logo ismartgate PRO\"><img decoding=\"async\" width=\"677\" height=\"100\" alt=\"ismartgate PRO - Apriporta intelligente per cancelli e garage\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo.png\" class=\"lazyload img-responsive wp-image-9078\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27677%27%20height%3D%27100%27%20viewBox%3D%270%200%20677%20100%27%3E%3Crect%20width%3D%27677%27%20height%3D%27100%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo-200x30.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo-400x59.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo-600x89.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismartgate_PRO_logo.png 677w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 677px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-14 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-26 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-medium button-default fusion-button-default button-3 fusion-button-default-span fusion-button-default-type\" style=\"--button_text_transform:capitalize;\" target=\"_self\" href=\"\/it\/acquistare-un-garage-intelligente\/\"><i class=\"fa-shopping-cart fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">ACQUISTA ORA<\/span><\/a><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><div class=\"fusion-text fusion-text-25\" style=\"--awb-text-transform:none;\"><h2 style=\"text-align: center;\">Scarica il manuale di istruzioni per l'apripista Automatic Technology NES-24V2 NeoSlider<\/h2>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><div class=\"fusion-text fusion-text-26\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center;\">Fare clic sul link sottostante per scaricare il manuale di istruzioni di Automatic Technology NES-24V2 NeoSlider<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-small button-default fusion-button-default button-4 fusion-button-default-span fusion-button-default-type\" style=\"--button_text_transform:capitalize;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/ismartgate.com\/manuals\/Automatic_Technology_NES-24V2_NeoSlider_manual.pdf\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Scarica il manuale di Automatic Technology NES-24V2 NeoSlider<\/span><\/a><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-44686","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Automatic Technology NES-24V2 NeoSlider Instruction Manual - ismartgate<\/title>\n<meta name=\"description\" content=\"Download the latest user manuals for your Automatic Technology NES-24V2 NeoSlider garage door or gate opener. Learn how to make your opener smart with ismartgate. Access installation guides, troubleshooting tips, and firmware updates to ensure optimal performance and security of your device. Get the support you need today to make operating your Automatic Technology opener effortless.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ismartgate.com\/it\/manuale-distruzione-della-tecnologia-automatica-nes-24v2-neoslider\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automatic Technology NES-24V2 NeoSlider Instruction Manual\" \/>\n<meta property=\"og:description\" content=\"Download the latest user manuals for your Automatic Technology NES-24V2 NeoSlider garage door or gate opener. Learn how to make your opener smart with ismartgate. Access installation guides, troubleshooting tips, and firmware updates to ensure optimal performance and security of your device. Get the support you need today to make operating your Automatic Technology opener effortless.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ismartgate.com\/it\/manuale-distruzione-della-tecnologia-automatica-nes-24v2-neoslider\/\" \/>\n<meta property=\"og:site_name\" content=\"ismartgate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ismartgateofficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-10T10:17:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ismartgate_ww\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/automatic-technology-nes-24v2-neoslider-instruction-manual\\\/\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/automatic-technology-nes-24v2-neoslider-instruction-manual\\\/\",\"name\":\"Automatic Technology NES-24V2 NeoSlider Instruction Manual - ismartgate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#website\"},\"datePublished\":\"2024-05-08T13:19:32+00:00\",\"dateModified\":\"2024-06-10T10:17:09+00:00\",\"description\":\"Download the latest user manuals for your Automatic Technology NES-24V2 NeoSlider garage door or gate opener. Learn how to make your opener smart with ismartgate. Access installation guides, troubleshooting tips, and firmware updates to ensure optimal performance and security of your device. Get the support you need today to make operating your Automatic Technology opener effortless.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/automatic-technology-nes-24v2-neoslider-instruction-manual\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ismartgate.com\\\/automatic-technology-nes-24v2-neoslider-instruction-manual\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/automatic-technology-nes-24v2-neoslider-instruction-manual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ismartgate.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Automatic Technology NES-24V2 NeoSlider Instruction Manual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#website\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/\",\"name\":\"ismartgate\",\"description\":\"The best Smart Garage Door Opener compatible with Apple HomeKit\",\"publisher\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#organization\",\"name\":\"ismartgate\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ismartgate_header_logo_2x.gif\",\"contentUrl\":\"https:\\\/\\\/ismartgate.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ismartgate_header_logo_2x.gif\",\"width\":378,\"height\":56,\"caption\":\"ismartgate\"},\"image\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ismartgateofficial\\\/\",\"https:\\\/\\\/x.com\\\/ismartgate_ww\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY7edN3zimmxIXJ3tnFMp8A\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Manuale di istruzioni di Automatic Technology NES-24V2 NeoSlider - ismartgate","description":"Scaricate i manuali d'uso pi\u00f9 recenti per il vostro apricancello o porta da garage Automatic Technology NES-24V2 NeoSlider. Scoprite come rendere intelligente il vostro apriporta con ismartgate. Accedete a guide all'installazione, suggerimenti per la risoluzione dei problemi e aggiornamenti del firmware per garantire prestazioni e sicurezza ottimali del vostro dispositivo. Ottenete oggi stesso il supporto di cui avete bisogno per far funzionare senza problemi il vostro apriporta Automatic Technology.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ismartgate.com\/it\/manuale-distruzione-della-tecnologia-automatica-nes-24v2-neoslider\/","og_locale":"it_IT","og_type":"article","og_title":"Automatic Technology NES-24V2 NeoSlider Instruction Manual","og_description":"Download the latest user manuals for your Automatic Technology NES-24V2 NeoSlider garage door or gate opener. Learn how to make your opener smart with ismartgate. Access installation guides, troubleshooting tips, and firmware updates to ensure optimal performance and security of your device. Get the support you need today to make operating your Automatic Technology opener effortless.","og_url":"https:\/\/ismartgate.com\/it\/manuale-distruzione-della-tecnologia-automatica-nes-24v2-neoslider\/","og_site_name":"ismartgate","article_publisher":"https:\/\/www.facebook.com\/ismartgateofficial\/","article_modified_time":"2024-06-10T10:17:09+00:00","twitter_card":"summary_large_image","twitter_site":"@ismartgate_ww","twitter_misc":{"Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ismartgate.com\/automatic-technology-nes-24v2-neoslider-instruction-manual\/","url":"https:\/\/ismartgate.com\/automatic-technology-nes-24v2-neoslider-instruction-manual\/","name":"Manuale di istruzioni di Automatic Technology NES-24V2 NeoSlider - ismartgate","isPartOf":{"@id":"https:\/\/ismartgate.com\/#website"},"datePublished":"2024-05-08T13:19:32+00:00","dateModified":"2024-06-10T10:17:09+00:00","description":"Scaricate i manuali d'uso pi\u00f9 recenti per il vostro apricancello o porta da garage Automatic Technology NES-24V2 NeoSlider. Scoprite come rendere intelligente il vostro apriporta con ismartgate. Accedete a guide all'installazione, suggerimenti per la risoluzione dei problemi e aggiornamenti del firmware per garantire prestazioni e sicurezza ottimali del vostro dispositivo. Ottenete oggi stesso il supporto di cui avete bisogno per far funzionare senza problemi il vostro apriporta Automatic Technology.","breadcrumb":{"@id":"https:\/\/ismartgate.com\/automatic-technology-nes-24v2-neoslider-instruction-manual\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ismartgate.com\/automatic-technology-nes-24v2-neoslider-instruction-manual\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ismartgate.com\/automatic-technology-nes-24v2-neoslider-instruction-manual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ismartgate.com\/"},{"@type":"ListItem","position":2,"name":"Automatic Technology NES-24V2 NeoSlider Instruction Manual"}]},{"@type":"WebSite","@id":"https:\/\/ismartgate.com\/#website","url":"https:\/\/ismartgate.com\/","name":"ismartgate","description":"Il miglior apriporta per garage intelligente compatibile con Apple HomeKit","publisher":{"@id":"https:\/\/ismartgate.com\/#organization"},"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ismartgate.com\/#organization","name":"ismartgate","url":"https:\/\/ismartgate.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ismartgate.com\/#\/schema\/logo\/image\/","url":"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ismartgate_header_logo_2x.gif","contentUrl":"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ismartgate_header_logo_2x.gif","width":378,"height":56,"caption":"ismartgate"},"image":{"@id":"https:\/\/ismartgate.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ismartgateofficial\/","https:\/\/x.com\/ismartgate_ww","https:\/\/www.youtube.com\/channel\/UCY7edN3zimmxIXJ3tnFMp8A"]}]}},"_links":{"self":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/pages\/44686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/comments?post=44686"}],"version-history":[{"count":2,"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/pages\/44686\/revisions"}],"predecessor-version":[{"id":50892,"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/pages\/44686\/revisions\/50892"}],"wp:attachment":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/media?parent=44686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}