{"id":38979,"date":"2023-10-22T10:02:29","date_gmt":"2023-10-22T10:02:29","guid":{"rendered":"https:\/\/ismartgate.com\/smart-garage-door-opener-for-bd-controll-a-door-s\/"},"modified":"2023-10-22T10:02:29","modified_gmt":"2023-10-22T10:02:29","slug":"apriporta-da-garage-intelligente-per-bd-controllare-una-porta-s","status":"publish","type":"page","link":"https:\/\/ismartgate.com\/it\/smart-garage-door-opener-for-bd-controll-a-door-s\/","title":{"rendered":"Apriporta da garage intelligente per B&amp;D Controll-A-Door S"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><h1 style=\"color: #000000; font-size: 27pt; letter-spacing: -1px; text-align: center;\">Come realizzare un <span style=\"color: #00ccff;\">B&amp;D Controll-A-Porta S<\/span> intelligente?<\/h1>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-text-transform:none;\"><p style=\"text-align: left;\"><span style=\"font-size: 13pt;\"><br \/>\nIl B&amp;D Controll-A-Door S \u00e8 un apriporta per garage altamente affidabile e popolare prodotto da B&amp;D. Conosciuto per la sua durata e le sue prestazioni efficienti, questo apriporta si \u00e8 guadagnato una solida reputazione tra i clienti di tutto il mondo. Con il suo design elegante e le sue funzioni avanzate, il B&amp;D Controll-A-Door S offre comodit\u00e0 e sicurezza al vostro garage.<br \/>\nOra potete portare il vostro B&amp;D Controll-A-Door S a un livello superiore rendendolo intelligente. \u00c8 stato presentato l'ismartgate, un accessorio per l'apertura intelligente della porta del garage che si integra perfettamente con il B&amp;D Controll-A-Door S. Con l'ismartgate \u00e8 possibile controllare e monitorare la porta del garage da qualsiasi luogo utilizzando il proprio smartphone.<br \/>\nCollegando il dispositivo ismartgate al vostro B&amp;D Controll-A-Door S, potrete usufruire di una serie di funzioni intelligenti. Aprite e chiudete la porta del garage a distanza, ricevete notifiche in tempo reale sul vostro telefono ogni volta che la porta viene aperta e concedete persino l'accesso temporaneo ai familiari o al personale addetto alle consegne. Con ismartgate, potrete stare tranquilli sapendo che il vostro garage \u00e8 sicuro e facilmente accessibile.<br \/>\nL'impostazione dell'ismartgate \u00e8 semplice e immediata. \u00c8 sufficiente installare il dispositivo, scaricare l'applicazione ismartgate e seguire le istruzioni passo-passo. L'app offre un'interfaccia intuitiva che consente di personalizzare le impostazioni, monitorare l'attivit\u00e0 della porta e gestire pi\u00f9 porte di garage, se necessario.<br \/>\nAggiornate il vostro B&amp;D Controll-A-Door S a un apriporta da garage intelligente con ismartgate. Provate la comodit\u00e0, la sicurezza e la tranquillit\u00e0 che derivano dal controllo completo della porta del garage da qualsiasi luogo e in qualsiasi momento.<br \/>\n<\/span><\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-image-element fusion-no-medium-visibility\" style=\"text-align:center;--awb-margin-top:0px;--awb-margin-right:0px;--awb-margin-bottom:0px;--awb-margin-left:0px;--awb-max-width:700px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"950\" height=\"460\" alt=\"Rendere intelligente l&#039;apertura del garage o del cancello esistente\" title=\"Creare un apriporta da garage intelligente\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/Make_a_Smart_garage_door_opener.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/Make_a_Smart_garage_door_opener.png\" class=\"lazyload img-responsive wp-image-11404\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27950%27%20height%3D%27460%27%20viewBox%3D%270%200%20950%20460%27%3E%3Crect%20width%3D%27950%27%20height%3D%27460%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/Make_a_Smart_garage_door_opener-200x97.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/Make_a_Smart_garage_door_opener-400x194.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/Make_a_Smart_garage_door_opener-600x291.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/Make_a_Smart_garage_door_opener-800x387.png 800w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/Make_a_Smart_garage_door_opener.png 950w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 950px\" \/><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\" style=\"--awb-text-transform:none;\"><h2 style=\"color: #000000; font-size: 23pt; letter-spacing: -1px; text-align: center;\">Cosa pu\u00f2 fare l'apriporta del garage ismartgate?<\/h2>\n<\/div><ul style=\"--awb-size:16px;--awb-line-height:27.2px;--awb-icon-width:27.2px;--awb-icon-height:27.2px;--awb-icon-margin:11.2px;--awb-content-margin:38.4px;\" class=\"fusion-checklist fusion-checklist-1 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\nScoprite i vantaggi dell'utilizzo dell'apriporta per garage ismartgate:<\/p>\n<ul>\n<li>Controllate la porta del garage a distanza con il vostro smartphone.<\/li>\n<li>Monitorare lo stato della porta del garage in tempo reale.<\/li>\n<li>Ricevere notifiche istantanee quando la porta del garage si apre o si chiude.<\/li>\n<li>Integrazione con assistenti vocali come Amazon Alexa e Google Assistant per un controllo a mani libere.<\/li>\n<li>Impostare orari personalizzati per aprire o chiudere automaticamente la porta del garage.<\/li>\n<li>Concedere l'accesso temporaneo a familiari, amici o personale addetto alle consegne.<\/li>\n<li>Integrazione con i sistemi smart home per creare scenari di automazione avanzati.<\/li>\n<li>Migliorate la sicurezza con funzioni come la registrazione video e il rilevamento del movimento.<\/li>\n<\/ul>\n<\/div><\/li><\/ul><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-4\" style=\"--awb-text-transform:none;\"><h2 style=\"color: #000000; font-size: 22pt; letter-spacing: -1px; text-align: center;\">Come si installa un'apertura di garage intelligente ismartgate in un B&amp;D Controll-A-Door S?<\/h2>\n<\/div><ul style=\"--awb-size:18px;--awb-line-height:30.6px;--awb-icon-width:30.6px;--awb-icon-height:30.6px;--awb-icon-margin:12.6px;--awb-content-margin:43.2px;\" class=\"fusion-checklist fusion-checklist-2 fusion-checklist-default type-icons\"><li class=\"fusion-li-item\" style=\"\"><span class=\"icon-wrapper circle-no\"><i class=\"fusion-li-icon awb-icon-check\" aria-hidden=\"true\"><\/i><\/span><div class=\"fusion-li-item-content\">\n<ol>\n<li>Prendi il tuo <a href=\"#buy\">dispositivo ismartgate qui<\/a>.<\/li>\n<li>Di seguito viene riportato lo schema di cablaggio di B&amp;D Controll-A-Door S.<\/li>\n<li>Con un piccolo cacciavite a croce, collegare i fili (inclusi nel kit ismartgate).<\/li>\n<li>Per alimentare il dispositivo ismartgate, \u00e8 possibile utilizzare l'adattatore CA da parete incluso. Nel caso in cui non si disponga di una presa di corrente, \u00e8 possibile utilizzare il nostro <a href=\"#buy\">Convertitore di potenza CC\/CC.<\/a><\/li>\n<\/ol>\n<\/div><\/li><\/ul><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element fusion-no-medium-visibility\" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"650\" height=\"520\" alt=\"Schema di cablaggio e collegamenti per iSmartgate Lite, Mini, Pro - Aperture per porte e cancelli di garage intelligenti\" title=\"Schema di cablaggio e collegamenti per iSmartgate Lite, Mini, Pro\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update.png\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update.png\" class=\"lazyload img-responsive wp-image-1951\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27650%27%20height%3D%27520%27%20viewBox%3D%270%200%20650%20520%27%3E%3Crect%20width%3D%27650%27%20height%3D%27520%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update-200x160.png 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update-400x320.png 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update-600x480.png 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/08\/isg_connections_diagram_update.png 650w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 650px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center;\"><span style=\"font-size: 21.3333px;\">Schema di cablaggio di B&amp;D Controll-A-Door S.<\/span><\/p>\n<p><img decoding=\"async\" id=\"brand-model-img\" class=\"img-center img-responsive lazyloaded\" title=\"Schema di collegamento per B&amp;D Controll-A-Door S\" src=\"https:\/\/ismartgate.com\/gates.ismartgate-images\/img_77_Controll-A-Door S.png\" alt=\"Schema di collegamento per B&amp;D Controll-A-Door S\" data-orig-src=\"https:\/\/ismartgate.com\/gates.ismartgate-images\/img_77_Controll-A-Door S.png\" \/><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-menu-anchor buy\" id=\"buy\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:20px;--awb-margin-top:0px;--awb-margin-bottom:-25px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:20px;margin-bottom:20px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-6\" style=\"--awb-text-transform:none;\"><h1 style=\"text-align: center; color: #3e4541; font-size: 26pt; letter-spacing: -1px; line-height: normal;\">Acquista il miglior garage intelligente Apple HomeKit<\/h1>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-7\"><p style=\"text-align: center; font-size: 8pt; letter-spacing: 1pt;\"><strong>NESSUN COSTO NASCOSTO O HARDWARE AGGIUNTIVO.<\/strong><\/p>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:20px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:250px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"268\" height=\"56\" title=\"ismartgate_official_store\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/05\/ismartgate_official_store.jpg\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/05\/ismartgate_official_store.jpg\" alt class=\"lazyload img-responsive wp-image-21193\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27268%27%20height%3D%2756%27%20viewBox%3D%270%200%20268%2056%27%3E%3Crect%20width%3D%27268%27%20height%3D%2756%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/05\/ismartgate_official_store-200x42.jpg 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/05\/ismartgate_official_store.jpg 268w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 268px\" \/><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-8\" style=\"--awb-text-transform:none;\"><h3 class=\"fusion-responsive-typography-calculated\" style=\"text-align: center; --fontsize: 14; line-height: 1.5;\" data-fontsize=\"25\" data-lineheight=\"37.5px\">Selezionate il vostro negozio:<\/h3>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_5 1_5 fusion-one-fifth fusion-column-first fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% + 4% + 4% + 4% ) * 0.2 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_1_5 1_5 fusion-one-fifth\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% + 4% + 4% + 4% ) * 0.2 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button-border-radius-top-left:7px;--button-border-radius-top-right:7px;--button-border-radius-bottom-right:7px;--button-border-radius-bottom-left:7px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/shop.ismartgate.com\/\"><i class=\"fa-shopping-cart fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">USA + Canada<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:120px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/shop.ismartgate.com\/\" target=\"_blank\" aria-label=\"negozio_paesi_usa_canada\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"213\" height=\"41\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27213%27%20height%3D%2741%27%20viewBox%3D%270%200%20213%2041%27%3E%3Crect%20width%3D%27213%27%20height%3D%2741%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2023\/05\/shop_countries_usa_canada.gif\" alt class=\"lazyload img-responsive wp-image-37643\"\/><\/a><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_5 1_5 fusion-one-fifth\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% + 4% + 4% + 4% ) * 0.2 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" style=\"--button-border-radius-top-left:7px;--button-border-radius-top-right:7px;--button-border-radius-bottom-right:7px;--button-border-radius-bottom-left:7px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/shopeurope.ismartgate.com\/\"><i class=\"fa-shopping-cart fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Europa<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:200px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/shopeurope.ismartgate.com\/\" target=\"_blank\" aria-label=\"negozio_paesi_europei\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"363\" height=\"88\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27363%27%20height%3D%2788%27%20viewBox%3D%270%200%20363%2088%27%3E%3Crect%20width%3D%27363%27%20height%3D%2788%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2023\/05\/shop_countries_europe.gif\" alt class=\"lazyload img-responsive wp-image-37641\"\/><\/a><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_5 1_5 fusion-one-fifth\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% + 4% + 4% + 4% ) * 0.2 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-3 fusion-button-default-span fusion-button-default-type\" style=\"--button-border-radius-top-left:7px;--button-border-radius-top-right:7px;--button-border-radius-bottom-right:7px;--button-border-radius-bottom-left:7px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/shopaustralia.ismartgate.com\/\"><i class=\"fa-shopping-cart fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Pacifico<\/span><\/a><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:165px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-6 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/shopaustralia.ismartgate.com\/\" target=\"_blank\" aria-label=\"negozio_paesi_pacifici\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"291\" height=\"86\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27291%27%20height%3D%2786%27%20viewBox%3D%270%200%20291%2086%27%3E%3Crect%20width%3D%27291%27%20height%3D%2786%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2023\/05\/shop_countries_pacific.gif\" alt class=\"lazyload img-responsive wp-image-37642\"\/><\/a><\/span><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_1_5 1_5 fusion-one-fifth fusion-column-last fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:20%;width:calc(20% - ( ( 4% + 4% + 4% + 4% ) * 0.2 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:35px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-first\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% + 4% ) * 0.33333333333333 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:140px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-7 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/www.amazon.com\/stores\/page\/C0C4B013-F3CC-4065-9A59-2F2F944EB5F2?ingress=0&amp;visitId=d94cec25-8f36-4c0e-8feb-4f82a089fc67&amp;ref_=ast_bln\" target=\"_blank\" aria-label=\"Il miglior apriporta da garage intelligente di Amazon\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"164\" height=\"101\" alt=\"Aprire il garage intelligente amazon\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27164%27%20height%3D%27101%27%20viewBox%3D%270%200%20164%20101%27%3E%3Crect%20width%3D%27164%27%20height%3D%27101%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2019\/05\/amazon_ismartgate_buy_smart_garage_opener.png\" class=\"lazyload img-responsive wp-image-1507\"\/><\/a><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-9\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center; text-decoration: underline !important;\"><strong><a href=\"https:\/\/www.amazon.com\/stores\/page\/C0C4B013-F3CC-4065-9A59-2F2F944EB5F2?ingress=0&#038;visitId=d94cec25-8f36-4c0e-8feb-4f82a089fc67&#038;ref_=ast_bln\" target=\"_blank\" rel=\"noopener noreferrer\">ismartgate USA Store &gt;<\/a><\/strong><\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-15 fusion_builder_column_1_3 1_3 fusion-one-third\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% + 4% ) * 0.33333333333333 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:140px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-8 hover-type-none\"><img decoding=\"async\" width=\"164\" height=\"101\" title=\"Amazon europa\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27164%27%20height%3D%27101%27%20viewBox%3D%270%200%20164%20101%27%3E%3Crect%20width%3D%27164%27%20height%3D%27101%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2024\/05\/Amazon-europa.png\" alt class=\"lazyload img-responsive wp-image-47223\"\/><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><script>\n\tfunction openLink() {\n\t\tvar selectElement = document.getElementById(\"linkDropdown\");\n        var selectedValue = selectElement.value;\n        if (selectedValue) {\n        \twindow.open(selectedValue, '_blank');\n          \tselectElement.value = \"\";\n        }\n\t}\n<\/script>\n<style>\n  #linkDropdown {\n    color: #0d89cc;\n    border: none;\n    font-stretch: normal;\n    font-weight: bold;\n    font-family: Lato;\n    text-decoration: underline !important;\n    font-size: 16px;\n    text-align: center;\n    cursor: pointer;\n  }\n<\/style>\n<div class=\"fusion-text fusion-text-4\" style=\"text-align: center; text-decoration: underline !important;\">\n  <select id=\"linkDropdown\" style=\"font-weight: bold !important; font-family: Lato !important;\" onchange=\"openLink()\">\n      <option value=\"\">Seleziona il negozio in Europa<\/option>\n      <option value=\"https:\/\/www.amazon.fr\/stores\/page\/EE62EBDF-C1F5-4DAE-A605-1BF22BE929E0\">ismartgate Francia Store<\/option>\n\n  <\/select>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-16 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% + 4% ) * 0.33333333333333 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:140px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-9 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/www.amazon.com\/stores\/page\/C0C4B013-F3CC-4065-9A59-2F2F944EB5F2?ingress=0&amp;visitId=d94cec25-8f36-4c0e-8feb-4f82a089fc67&amp;ref_=ast_bln\" target=\"_blank\" aria-label=\"amazon_ismartgate_buy_smart_garage_opener_UK\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"164\" height=\"101\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27164%27%20height%3D%27101%27%20viewBox%3D%270%200%20164%20101%27%3E%3Crect%20width%3D%27164%27%20height%3D%27101%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2023\/05\/amazon_ismartgate_buy_smart_garage_opener_UK.png\" alt class=\"lazyload img-responsive wp-image-37632\"\/><\/a><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-10\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center; text-decoration: underline !important;\"><strong><a href=\"https:\/\/www.amazon.co.uk\/stores\/node\/17178904031?ie=UTF8&amp;field-lbr_brands_browse-bin=ISMARTGATE\" target=\"_blank\" rel=\"noopener noreferrer\">ismartgate UK Store &gt;<\/a><\/strong><\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;margin-bottom:5px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-17 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:50px;margin-bottom:25px;width:100%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:1px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-11\" style=\"--awb-text-transform:none;\"><h2>Confronta gli apriporta da garage intelligenti ismartgate<\/h2>\n<\/div>\n<table id=\"tablepress-19\" class=\"tablepress tablepress-id-19\">\n<tbody>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2770%27%20height%3D%2734%27%20viewBox%3D%270%200%2070%2034%27%3E%3Crect%20width%3D%2770%27%20height%3D%2734%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/08\/mini.fw_.png\" alt=\"\" width=\"70\" height=\"34\" class=\"lazyload aligncenter size-full wp-image-17\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2770%27%20height%3D%2734%27%20viewBox%3D%270%200%2070%2034%27%3E%3Crect%20width%3D%2770%27%20height%3D%2734%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismargate_lite_logo.png\" alt=\"\" width=\"70\" height=\"34\" class=\"lazyload aligncenter size-full wp-image-17\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2757%27%20height%3D%2757%27%20viewBox%3D%270%200%2057%2057%27%3E%3Crect%20width%3D%2757%27%20height%3D%2757%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2021\/07\/ismargate_pro_logo.png\" alt=\"\" width=\"57\" height=\"57\" class=\"lazyload aligncenter size-full wp-image-17\" \/><\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Porte supportate<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">1<\/td><td class=\"column-4\">3<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Avvisi di accesso remoto e di stato della porta<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Apple HomeKit<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Assistente Google<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Samsung SmartThings<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\"><span style=\"color:red;\">IFTTT***<\/span><\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Amazon Alexa*<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Compatibilit\u00e0 dei sensori wireless<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Compatibilit\u00e0 dei sensori cablati<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Gestione degli utenti<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Integrazione video<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Allarme acustico visivo<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Aprire e chiudere la musica personalizzata<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Compatibilit\u00e0 Wi-Fi (2,4GHz)<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Compatibilit\u00e0 Ethernet**<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Accesso al browser web<\/td><td class=\"column-2\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2717%27%20height%3D%2716%27%20viewBox%3D%270%200%2017%2016%27%3E%3Crect%20width%3D%2717%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/no.png\" alt=\"\" width=\"17\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-159\" \/><\/td><td class=\"column-3\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td><td class=\"column-4\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%2720%27%20height%3D%2716%27%20viewBox%3D%270%200%2020%2016%27%3E%3Crect%20width%3D%2720%27%20height%3D%2716%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ok.png\" alt=\"\" width=\"20\" height=\"16\" class=\"lazyload aligncenter size-full wp-image-160\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-19 from cache --><div class=\"fusion-text fusion-text-12\" style=\"--awb-text-transform:none;\"><h6>*L'\"abilit\u00e0 ismartgate\" \u00e8 disponibile nelle seguenti lingue: Italiano (IT),Tedesco (DE),Inglese (US),Spagnolo (ES),Spagnolo (US),Francese (FR),Inglese (UK\/IE)<\/h6>\n<\/div><div class=\"fusion-text fusion-text-13\" style=\"--awb-text-transform:none;\"><h6>**<a href=\"https:\/\/ismartgate.com\/it\/accessori-per-garage-intelligenti\/#network\" target=\"_blank\" rel=\"noopener\">Da USB a Ethernet<\/a> per collegare l'iSmartgate al router con un cavo Ethernet.<\/h6>\n<\/div><div class=\"fusion-text fusion-text-14\" style=\"--awb-text-transform:none;\"><h6>***<span data-teams=\"true\">Il 1\u00b0 ottobre 2025<\/span><span data-teams=\"true\">\u00a0l'integrazione di iSmartGate con IFTTT sar\u00e0 interrotta. Il servizio iSmartGate su IFTTT non sar\u00e0 pi\u00f9 disponibile dopo questa data. Ci scusiamo per gli eventuali disagi che ci\u00f2 potrebbe causare.<\/span><\/h6>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-menu-anchor\" id=\"simulator\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:-60px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-18 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:-30px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-15\" style=\"--awb-text-transform:none;\"><h2 style=\"color: #000000; font-size: 26pt; letter-spacing: -1px; text-align: center;\">Di quale ismartgate ho bisogno?<\/h2>\n<\/div><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-max-width:640px;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-10 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/ismartgate.com\/it\/matter-garage-door\/\" target=\"_self\" aria-label=\"trova_il_tuo_mutuo_mobile\"><img decoding=\"async\" width=\"1010\" height=\"470\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/find_your_ismartgate_mobile.jpg\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/find_your_ismartgate_mobile.jpg\" alt class=\"lazyload img-responsive wp-image-10958\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271010%27%20height%3D%27470%27%20viewBox%3D%270%200%201010%20470%27%3E%3Crect%20width%3D%271010%27%20height%3D%27470%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/find_your_ismartgate_mobile-200x93.jpg 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/find_your_ismartgate_mobile-400x186.jpg 400w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/find_your_ismartgate_mobile-600x279.jpg 600w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/find_your_ismartgate_mobile-800x372.jpg 800w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/find_your_ismartgate_mobile.jpg 1010w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 1010px\" \/><\/a><\/span><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:0px;margin-bottom:10px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-11 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-margin-top:30px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-19 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-first\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:0px;width:25%;width:calc(25% - ( ( 4% + 4% ) * 0.25 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-11 hover-type-none\"><img decoding=\"async\" width=\"270\" height=\"244\" alt=\"Di quale apriporta per garage iSmartgate ho bisogno?\" title=\"Di quale apriporta per garage iSmartgate ho bisogno?\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_home.jpg\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_home.jpg\" class=\"lazyload img-responsive wp-image-10961\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27270%27%20height%3D%27244%27%20viewBox%3D%270%200%20270%20244%27%3E%3Crect%20width%3D%27270%27%20height%3D%27244%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_home-200x181.jpg 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_home.jpg 270w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 270px\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-20 fusion_builder_column_1_2 1_2 fusion-one-half\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:0px;width:50%;width:calc(50% - ( ( 4% + 4% ) * 0.5 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-text fusion-text-16\" style=\"--awb-text-transform:none;\"><h2 style=\"color: #000000; font-size: 26pt; letter-spacing: -1px; text-align: center;\">Di quale ismartgate ho bisogno?<\/h2>\n<\/div><div class=\"fusion-text fusion-text-17\" style=\"--awb-text-transform:none;\"><p style=\"text-align: center;\"><span style=\"font-size: 16pt; color: #000!important;\">Provate il nostro simulatore e trovate l'ismartgate perfetto per la vostra casa.<br \/>\n<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-21 fusion_builder_column_1_4 1_4 fusion-one-fourth fusion-column-last\" style=\"--awb-padding-top:0px;--awb-padding-bottom:0px;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-margin-bottom:0px;width:25%;width:calc(25% - ( ( 4% + 4% ) * 0.25 ) );\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-element fusion-image-align-center in-legacy-container\" style=\"text-align:center;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><div class=\"imageframe-align-center\"><span class=\"fusion-imageframe imageframe-none imageframe-12 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/ismartgate.com\/it\/matter-garage-door\/\" target=\"_self\" aria-label=\"Di quale apriporta iSmartgate ho bisogno?\"><img decoding=\"async\" width=\"270\" height=\"244\" alt=\"Di quale apriporta iSmartgate ho bisogno?\" src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_house.jpg\" data-orig-src=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_house.jpg\" class=\"lazyload img-responsive wp-image-10962\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27270%27%20height%3D%27244%27%20viewBox%3D%270%200%20270%20244%27%3E%3Crect%20width%3D%27270%27%20height%3D%27244%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_house-200x181.jpg 200w, https:\/\/ismartgate.com\/wp-content\/uploads\/2022\/04\/which_is_the_best_smart_garage_for_my_house.jpg 270w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 800px) 100vw, 270px\" \/><\/a><\/span><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-12 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-custom-z-index\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-z-index:10;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-22 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-blend:overlay;--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;width:100%;\"><div class=\"fusion-separator-border sep-double\" style=\"--awb-height:20px;--awb-amount:20px;border-color:#e0dede;border-top-width:0px;border-bottom-width:0px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><input type=\"radio\" style=\"display:none;\" id=\"option-yes\" checked=\"checked\" name=\"option-smart\"\n       class=\"option-smart\" value=\"1\" \/>\n<!------------ ------>\n<div class=\"row row-doors row-green\">\n    <div class=\"col-sm-2 col-xs-2 pd-tb-20\">\n        <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n             src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/garage_icon.png\" alt=\"ismartgate - il miglior apriporta per garage\" \/>\n    <\/div>\n    <div class=\"col-sm-8 col-xs-6 pd-tb-20\">\n        <p><span class=\"fusion-no-small-visibility\">Quanti <\/span>Porte di garage<span\n                class=\"fusion-no-small-visibility\"> avete?<\/span><\/p>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 pd-tb-20\">\n        <select id=\"num_garage_doors\">\n            <option value=\"0\">0<\/option>\n            <option value=\"1\">1<\/option>\n            <option value=\"2\">2<\/option>\n            <option value=\"3\">3<\/option>\n        <\/select>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 line-left\">\n        <i class=\"fa fa-chevron-down\" src=\"\" id=\"collapse-block-green\"><\/i>\n    <\/div>\n<\/div>\n<div class=\"block-green row\">\n    <div class=\"col-xs-12\">\n        <div class=\"row\">\n            <!-- modelos de puertas -->\n            <div id=\"garage-1\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/garage_sectional.png\"\n                         class=\"lazyload img-center img-responsive\" alt=\"apriporta sezionale per garage\"\/>\n                <\/div>\n                <p class=\"door-title\">PORTA 1 TIPO:<\/p>\n                <p class=\"door-model\" id=\"garage-door-model-1\">Sezionale<\/p>\n                <p class=\"door-model-description\" id=\"garage-door-model-description-1\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-type-garage\" data-number=\"1\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-type-garage\" data-number=\"1\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"garage-1-selected\" value=\"1\" \/>\n            <\/div>\n            <div id=\"garage-2\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/garage_sectional.png\"\n                         class=\"lazyload img-center img-responsive\" alt=\"apriporta sezionale per garage\"\/>\n                <\/div>\n                <p class=\"door-title\">PORTA 2 TIPO:<\/p>\n                <p class=\"door-model\" id=\"garage-door-model-2\">Sezionale<\/p>\n                <p class=\"door-model-description\" id=\"garage-door-model-description-2\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-type-garage\" data-number=\"2\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-type-garage\" data-number=\"2\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"garage-2-selected\" value=\"1\" \/>\n            <\/div>\n            <div id=\"garage-3\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/garage_sectional.png\"\n                         class=\"lazyload img-center img-responsive\" alt=\"apriporta sezionale per garage\"\/>\n                <\/div>\n                <p class=\"door-title\">PORTA 3 TIPO:<\/p>\n                <p class=\"door-model\" id=\"garage-door-model-3\">Sezionale<\/p>\n                <p class=\"door-model-description\" id=\"garage-door-model-description-3\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-type-garage\" data-number=\"3\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-type-garage\" data-number=\"3\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"garage-3-selected\" value=\"1\" \/>\n            <\/div>\n        <\/div>\n\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"garage-sensor-type\">\n                <!-- separacion -->\n                <p class=\"title-section\">Tipo di sensore<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/img-sensor-type.png\" alt=\"Simulatore di porta di garage ismartgate, tipo sensore\"\n                         id=\"img-sensor-type-garage\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete uno o pi\u00f9 sensori wireless o cablati per la\/e porta\/e del garage? <\/p>\n                <p class=\"descrip-section\"><\/p>\n                <select class=\"sel-separation\" id=\"sensor-type-garage\">\n                    <option value=\"0\">Sensore wireless<\/option>\n                    <option value=\"1\">Sensore cablato<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"garage-security\">\n                <!-- video -->\n                <p class=\"title-section\">Il vostro apriporta \u00e8 Chamberlain, Liftmaster o Craftsman?<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/security.png\" alt=\"Simulatore di porta di garage ismartgate, sicurezza\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Avete un apriporta di garage Chamberlain o LiftMaster con Security+2.0?<\/p>\n                <p class=\"descrip-section\">Controllate il colore del pulsante di apprendimento sul vostro apri garage. Se \u00e8 giallo, il vostro apriporta utilizza il sistema Security+2.0 e avrete bisogno dell'adattatore per interruttori ismartgate.<\/p>\n                <form action=\"\">\n                    <div class=\"row\" style=\"max-width: 420px;margin: auto;\">\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-security-1\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 1<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-security-2\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 2<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-security-3\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 3<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n            <\/div>\n        <\/div>\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"garage-separation\">\n                <!-- separacion -->\n                <p class=\"title-section\">Separazione<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/garage_separation.gif\" alt=\"Simulatore di porta di garage ismartgate, 3 porte separate\"\n                         id=\"img-separation-garage\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Le porte del garage sono collegate? <i\n                        onclick=\"ShowModalProd('\/images\/simulator\/separation.gif','Separation','')\"\n                        class=\"grey-icon fa fa-question-circle-o\"><\/i><\/p>\n                <p class=\"descrip-section\">Se i garage non hanno pareti di separazione sono considerati\n                    \"collegato\"<\/p>\n                <select class=\"sel-separation\" id=\"number-separation-garage\">\n                    <option value=\"0\">S\u00ec<\/option>\n                    <option value=\"1\">1 Separazione<\/option>\n                    <option value=\"2\" id=\"garage-sep-2-option\">2 Separazioni<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"garage-video\">\n                <!-- video -->\n                <p class=\"title-section\">Video in diretta<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/video.png\" alt=\"simulatore di porta di garage ismartgate, video\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete vedere cosa succede nel vostro garage in tempo reale?<\/p>\n                <p class=\"descrip-section\">Controllate le porte del garage con un video in diretta nell'app<\/p>\n                <form action=\"\">\n                    <div class=\"row\" style=\"max-width: 420px;margin: auto;\">\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-cam-1\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 1<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-cam-2\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 2<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"garage-cam-3\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 3<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n<\/div>\n<!------------ ------>\n<div class=\"row row-doors row-blue\">\n    <div class=\"col-sm-2 col-xs-2 pd-tb-20\">\n        <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n             src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/gate_icon.png\" alt=\"apricancello ismartgate con telecamera\" \/>\n    <\/div>\n    <div class=\"col-sm-8 col-xs-6 pd-tb-20\">\n        <p><span class=\"fusion-no-small-visibility\">Quanti <\/span>Cancelli<span\n                class=\"fusion-no-small-visibility\"> avete?<\/span><\/p>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2  pd-tb-20\">\n        <select id=\"num_gate_doors\">\n            <option value=\"0\">0<\/option>\n            <option value=\"1\">1<\/option>\n            <option value=\"2\">2<\/option>\n            <option value=\"3\">3<\/option>\n        <\/select>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 line-left\">\n        <i class=\"fa fa-chevron-down\" src=\"\" id=\"collapse-block-blue\"><\/i>\n    <\/div>\n<\/div>\n<div class=\"block-blue row\">\n    <div class=\"col-xs-12\">\n        <div class=\"row\">\n            <!-- modelos de puertas -->\n            <div id=\"gate-1\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/gate_sliding.png\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"door-title\">PORTA 1 TIPO:<\/p>\n                <p class=\"door-model\" id=\"gate-door-model-1\">Cancello scorrevole<\/p>\n                <p class=\"door-model-description\" id=\"gate-door-model-description-1\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-gate\" data-number=\"1\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-gate\" data-number=\"1\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"gate-1-selected\" value=\"6\" \/>\n            <\/div>\n            <div id=\"gate-2\" class=\"col-sm-4 col-xs-12 line-right\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/gate_sliding.png\" alt=\"simulatore ismartgate - cancello scorrevole\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"door-title\">PORTA 2 TIPO:<\/p>\n                <p class=\"door-model\" id=\"gate-door-model-2\">Cancello scorrevole<\/p>\n                <p class=\"door-model-description\" id=\"gate-door-model-description-2\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-gate\" data-number=\"2\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-gate\" data-number=\"2\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"gate-2-selected\" value=\"6\" \/>\n            <\/div>\n            <div id=\"gate-3\" class=\"col-sm-4 col-xs-12\">\n                <div class=\"type-img\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/door_model\/gate_sliding.png\" alt=\"simulatore ismartgate - cancello scorrevole\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"door-title\">PORTA 3 TIPO:<\/p>\n                <p class=\"door-model\" id=\"gate-door-model-3\">Cancello scorrevole<\/p>\n                <p class=\"door-model-description\" id=\"gate-door-model-description-3\"><\/p>\n                <div class=\"row\">\n                    <div class=\"col-xs-6\" style=\"text-align:right;\">\n                        <i class=\"fa fa-chevron-circle-left prev-gate\" data-number=\"3\"\n                           style=\"margin-right:2px;\"><\/i>\n                    <\/div>\n                    <div class=\"col-xs-6\" style=\"text-align:left;\">\n                        <i class=\"fa fa-chevron-circle-right next-gate\" data-number=\"3\"\n                           style=\"margin-left:2px;\"><\/i>\n                    <\/div>\n                <\/div>\n                <input type=\"hidden\" id=\"gate-3-selected\" value=\"6\" \/>\n            <\/div>\n        <\/div>\n\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"gate-sensor-type\">\n                <!-- separacion -->\n                <p class=\"title-section\">Tipo di sensore<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/img-sensor-type.png\" alt=\"Porta di simulazione ismartgate, tipo sensore\"\n                         id=\"img-sensor-type-gate\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete uno o pi\u00f9 sensori wireless o cablati per la\/e porta\/e del garage? <\/p>\n                <p class=\"descrip-section\"><\/p>\n                <select class=\"sel-separation\" id=\"sensor-type-gate\">\n                    <option value=\"0\">Sensore wireless<\/option>\n                    <option value=\"1\">Sensore cablato<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"gate-power\">\n                <!-- separacion -->\n                <p class=\"title-section\">Presa di corrente per cancello<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/img-power-outlet.png\" alt=\"Cancello di simulazione ismartgate, presa di alimentazione\"\n                         id=\"img-power-outlet-gate\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Avete una presa da 110V\/220V vicino al vostro cancello?<\/p>\n                <p class=\"descrip-section\">Se non si dispone di una presa di corrente da 110V\/220V vicino al cancello, \u00e8 necessario un convertitore di corrente DC\/DC per alimentare l'apriporta ismartgate.<\/p>\n                <select class=\"sel-separation\" id=\"power-outlet-gate\">\n                    <option value=\"0\">S\u00ec<\/option>\n                    <option value=\"1\">No<\/option>\n                <\/select>\n            <\/div>\n        <\/div>\n        <div class=\"row line-top\">\n            <div class=\"col-sm-6 line-right\" id=\"gate-separation\">\n                <!-- separacion -->\n                <p class=\"title-section\">Separazione<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/gate_separation_3_doors.png\" alt=\"simulatore di cancello ismartgate separazione 3 porte\"\n                         id=\"img-separation-gate\" class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">I vostri cancelli sono collegati?<\/p>\n                <p class=\"descrip-section\">Meno di 30 piedi sono considerati \"collegati\"<\/p>\n                <select class=\"sel-separation\" id=\"number-separation-gate\">\n                    <option value=\"0\">S\u00ec<\/option>\n                    <option value=\"1\">1 Separazione<\/option>\n                    <option value=\"2\" id=\"gate-sep-2-option\">2 Separazioni<\/option>\n                <\/select>\n            <\/div>\n            <div class=\"col-sm-6\" id=\"gate-video\">\n                <!-- video -->\n                <p class=\"title-section\">Video in diretta<\/p>\n                <div class=\"img-separation\">\n                    <img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/images\/simulator\/video.png\" alt=\"simulatore di porta di garage ismartgate, video\"\n                         class=\"lazyload img-center img-responsive\" \/>\n                <\/div>\n                <p class=\"subtitle-section\">Volete vedere cosa succede nel vostro gate in tempo reale?<\/p>\n                <p class=\"descrip-section\">Controllo dei cancelli con video in diretta nell'app<\/p>\n                <form action=\"\">\n                    <div class=\"row\" style=\"max-width: 420px;margin: auto;\">\n                        <div class=\"col-sm-4 col-xs-4\" id=\"gate-cam-1\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 1<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"gate-cam-2\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 2<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                        <div class=\"col-sm-4 col-xs-4\" id=\"gate-cam-3\">\n                            <div class=\"block-door-cam\">\n                                <label class=\"subtitle-section\">Porta 3<\/label>\n                                <select>\n                                    <option value=\"0\">No<\/option>\n                                    <option value=\"1\">S\u00ec<\/option>\n                                <\/select>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n<\/div>\n\n<!------------ ------>\n<div class=\"row row-doors row-red\">\n    <div class=\"col-sm-2 col-xs-2 pd-tb-20\">\n        <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n             style=\"width:52px;\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Icon_smarthomes.png\" alt=\"SmartHome\" \/>\n    <\/div>\n    <div class=\"col-sm-8 col-xs-8 pd-tb-20 smarthome-title\">\n        <p>Voglio che ismartgate sia compatibile con: <br \/>\n            <img decoding=\"async\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/click_to_select_deselect.gif\" alt=\"Fare clic per selezionare\/deselezionare l&#039;opzione di compatibilit\u00e0 dell&#039;apriporta del garage intelligente ismartgate con\" \/><\/p>\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 hidden-xs pd-tb-20\">\n\n    <\/div>\n    <div class=\"col-sm-1 col-xs-2 line-left\">\n        <i class=\"fa fa-chevron-up\" id=\"collapse-block-red\"><\/i>\n    <\/div>\n<\/div>\n<div class=\"block-red row\">\n    <div class=\"col-xs-6\">\n        <div class=\"row\">\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-Apple\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Apple_OFF.png\" alt=\"Apple Homekit compatibile con l&#039;apriporta del garage ismartgate\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"apple-homekit-option\" name=\"apple-homekit-option\" data-img=\"Apple\" value=\"0\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-Alexa\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Alexa_ON.png\" alt=\"Apriporta da garage intelligente compatibile con Amazon Alexa\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"alexa-option\" name=\"alexa-option\" checked=\"checked\" data-img=\"Alexa\" value=\"1\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-Google\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Google_ON.png\" alt=\"Apriporta da garage compatibile con l&#039;assistente Google\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"google-option\" name=\"google-option\" checked=\"checked\" data-img=\"Google\" value=\"1\" \/>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"col-xs-6\">\n        <div class=\"row\">\n            <div class=\"col-sm-4 col-xs-12 smart-option\">\n                <img decoding=\"async\" id=\"imgoption-SmartThings\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/SmartThings_OFF.png\" alt=\"Apriporta di garage intelligente compatibile con SmartThings\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"smartthings-option\" name=\"smartthings-option\" data-img=\"SmartThings\" value=\"0\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\" style=\"display: none\">\n                <img decoding=\"async\" id=\"imgoption-IFTTT\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/IFTTT_ON.png\" alt=\"Apriporta da garage intelligente compatibile con IFTTT\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"ifttt-option\" name=\"ifttt-option\" checked=\"checked\" data-img=\"IFTTT\" value=\"0\" \/>\n            <\/div>\n            <div class=\"col-sm-4 col-xs-12 smart-option\" style=\"display: none\">\n                <img decoding=\"async\" id=\"imgoption-none\" class=\"lazyload img-responsive img-center\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/none_OFF.png\" alt=\"Nessuno (non \u00e8 stata selezionata la compatibilit\u00e0 con Alexa, Apple HomeKit, Google assistant, SmartThings o IFTTT)\" \/>\n                <br class=\"hidden-xs\"\/>\n                <input type=\"radio\" id=\"none-option\" name=\"none-option\" data-img=\"none\" value=\"0\" \/>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<!------------ ------>\n\n<h6 class=\"text-center\">Se la vostra casa non corrisponde a queste opzioni, inviateci un'e-mail a <a\n        href=\"mailto:support@ismartgate.com\">support@ismartgate.com<\/a><\/h6>\n<br \/>\n<br \/><div class=\"fusion-button-wrapper fusion-aligncenter\"><a class=\"fusion-button button-flat button-medium button-custom fusion-button-default button-4 fusion-button-default-span fusion-button-default-type\" style=\"--button_accent_color:#ffffff;--button_accent_hover_color:#ffffff;--button_border_hover_color:#ffffff;--button_border_width-top:1px;--button_border_width-right:1px;--button_border_width-bottom:1px;--button_border_width-left:1px;--button_gradient_top_color:#0d89cc;--button_gradient_bottom_color:#0d89cc;--button_gradient_top_color_hover:#0a0303;--button_gradient_bottom_color_hover:#0a0303;\" target=\"_self\" id=\"btn_get_result\"><i class=\"fa-chevron-down fas awb-button__icon awb-button__icon--default button-icon-left\" aria-hidden=\"true\"><\/i><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Ottenere il risultato<\/span><\/a><\/div><div id=\"result-simulator\">\n                <div class=\"row row-white\">\n                    <div class=\"col-xs-12\">\n                        <p class=\"title-result\">RISULTATO FINALE<\/p>\n                    <\/div>\n                    <br \/>\n                    <div class=\"col-sm-12\" id=\"block-result-smart\">\n                        <div class=\"row\">\n                            <div class=\"col-sm-2 icon-door\">\n                                <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n                        style=\"width:52px;\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Icon_smarthomes.png\" alt=\"SmartHome\" \/>\n                            <\/div>\n                            <div class=\"col-sm-8 col-xs-12\">\n                                <div class=\"block-buy-center block-smart\">\n                                    <p class=\"title-section option-1-res\">Apriscatole Compatibile con: \n                                        <div class=\"block-res-img\">\n                                            <img decoding=\"async\" id=\"res-smart-img-apple-homekit\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Apple_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-alexa\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Alexa_ON.png\" alt=\"Alexa\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-google\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/Google_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-smartthings\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/SmartThings_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-ifttt\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/IFTTT_ON.png\" alt=\"Apple Homekit\" \/>\n                                            <img decoding=\"async\" id=\"res-smart-img-none\" class=\"lazyload img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/static_uploads\/icons-simulator\/none_ON.png\" alt=\"Alexa\" \/>\n                                        <\/div>\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-2 icon-door\"><\/div>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-sm-6 line-right\" id=\"block-result-garage\">\n                        <div class=\"row header-result\">\n                            <div class=\"col-sm-4 icon-door\">\n                                <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n                                    src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/garage_icon.png\" alt=\"ismartgate - il miglior apriporta per garage\"\/>\n                            <\/div>\n                            <div class=\"col-sm-8\">\n                                <div class=\"block-buy-center\">\n                                    <p class=\"title-result-section\">La vostra selezione per <span id=\"res_number_garage\">0<\/span>x GARAGE\n                                        PORTA<span id=\"res_s_garage\">S<\/span>:<\/p>\n                                    <p class=\"result-content\">\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"row line-bottom-xs\">\n                            <div class=\"col-sm-8 col-sm-offset-4 buy-result\">\n                                <div class=\"block-buy-center\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                    <div class=\"col-sm-6\" id=\"block-result-gate\">\n                        <div class=\"row header-result\">\n                            <div class=\"col-sm-8\">\n                                <div class=\"block-buy-center\">\n                                    <p class=\"title-result-section\">La vostra selezione per <span id=\"res_number_gate\">0<\/span>x GATE<span\n                                            id=\"res_s_gate\">S<\/span>:<\/p>\n                                    <p class=\"result-content\">\n                                    <\/p>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-sm-4 icon-door\">\n                                <img decoding=\"async\" class=\"lazyload img-responsive img-center\"\n                                    src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\/wp-content\/uploads\/2018\/05\/gate_icon.png\" \/>\n                            <\/div>\n                        <\/div>\n                        <div class=\"row\">\n                            <div class=\"col-sm-8 buy-result\">\n                                <div class=\"block-buy-center\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n        <div class=\"row row-grey\">\n            <p class=\"title-result\">COMPRARE TUTTO ORA:<\/p>\n            <p class=\"block-buttons buttons-isg\">\n              <a class=\"button-flat fusion-button-pill button-large button-default button-1\" href=\"\/it\/acquistare-un-garage-intelligente\/\" target=\"_blank\"><i class=\"fa-shopping-cart fas button-icon-left\"><\/i><span class=\"fusion-button-text\">ACQUISTA ORA<\/span><\/a>\n          <\/p>\n        <\/div>\n    <\/div><div id=\"overlay-buy\" style=\"display:none;\" onclick=\"HideModal()\"><\/div>\n<div id=\"block-buy\" style=\"display:none;\">\n    <span onclick=\"HideModal()\" id=\"close-modal-sim\" style=\"cursor:pointer;margin-top:-3px;margin-right:-3px;height: 20px !important;overflow: hidden;display: inherit;\">\n        <i style=\"font-size:20px;\" class=\"pull-right fa fa-close\"><\/i><\/span>\n        <h5><\/h5>\n        <p class=\"result-content\" style=\"margin-bottom:0;margin-top:0;\"><\/p>\n        <hr style=\"border: 1px solid #eee;margin-top:10px;margin-bottom:10px;\">\n        <img decoding=\"async\" class=\"lazyload img-center img-responsive\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAABAAEICTAEAOw==\" data-orig-src=\"\">\n<\/div>\n\n<link rel='stylesheet' id='cfaq-adminGlobal-css'  href='\/css\/simulator_4.css?v=1.1' type='text\/css' \/>\n<script src=\"https:\/\/code.jquery.com\/jquery-3.3.1.min.js\"\n\t\t\t  integrity=\"sha256-FgpCb\/KJQlLNfOu91ta32o\/NMZxltwRo8QtmkMRdAu8=\"\n\t\t\t  crossorigin=\"anonymous\"><\/script>\n<script type='text\/javascript'>\n\tjq_ggg = jQuery.noConflict( true );\n<\/script>\n<script type='text\/javascript' src='\/js\/simulator_4.js?v=1.2'><\/script><div class=\"fusion-clearfix\"><\/div><\/div><\/div>\n<\/div><\/div>\n<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-38979","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Smart garage door opener for B&amp;D Controll-A-Door S - ismartgate<\/title>\n<meta name=\"description\" content=\"You can make your B&amp;D model Controll-A-Door S garage door opener smart. All you need to do is install the ismartgate and wire it to the control board of your existing garage door opener.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ismartgate.com\/it\/apriporta-da-garage-intelligente-per-bd-controllare-una-porta-s\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart garage door opener for B&amp;D Controll-A-Door S\" \/>\n<meta property=\"og:description\" content=\"You can make your B&amp;D model Controll-A-Door S garage door opener smart. All you need to do is install the ismartgate and wire it to the control board of your existing garage door opener.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ismartgate.com\/it\/apriporta-da-garage-intelligente-per-bd-controllare-una-porta-s\/\" \/>\n<meta property=\"og:site_name\" content=\"ismartgate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ismartgateofficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ismartgate.com\/gates.ismartgate-images\/img_77_Controll-A-Door%20S.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ismartgate_ww\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/smart-garage-door-opener-for-bd-controll-a-door-s\\\/\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/smart-garage-door-opener-for-bd-controll-a-door-s\\\/\",\"name\":\"Smart garage door opener for B&D Controll-A-Door S - ismartgate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#website\"},\"datePublished\":\"2023-10-22T10:02:29+00:00\",\"description\":\"You can make your B&D model Controll-A-Door S garage door opener smart. All you need to do is install the ismartgate and wire it to the control board of your existing garage door opener.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/smart-garage-door-opener-for-bd-controll-a-door-s\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ismartgate.com\\\/smart-garage-door-opener-for-bd-controll-a-door-s\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/smart-garage-door-opener-for-bd-controll-a-door-s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ismartgate.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smart garage door opener for B&#038;D Controll-A-Door S\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#website\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/\",\"name\":\"ismartgate\",\"description\":\"The best Smart Garage Door Opener compatible with Apple HomeKit\",\"publisher\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#organization\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#organization\",\"name\":\"ismartgate\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ismartgate.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ismartgate_header_logo_2x.gif\",\"contentUrl\":\"https:\\\/\\\/ismartgate.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/ismartgate_header_logo_2x.gif\",\"width\":378,\"height\":56,\"caption\":\"ismartgate\"},\"image\":{\"@id\":\"https:\\\/\\\/ismartgate.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ismartgateofficial\\\/\",\"https:\\\/\\\/x.com\\\/ismartgate_ww\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCY7edN3zimmxIXJ3tnFMp8A\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Apriporta da garage intelligente per B&amp;D Controll-A-Door S - ismartgate","description":"\u00c8 possibile rendere intelligente il proprio apriporta di garage B&amp;D modello Controll-A-Door S. \u00c8 sufficiente installare l'ismartgate e collegarlo alla scheda di controllo dell'apriporta del garage esistente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ismartgate.com\/it\/apriporta-da-garage-intelligente-per-bd-controllare-una-porta-s\/","og_locale":"it_IT","og_type":"article","og_title":"Smart garage door opener for B&D Controll-A-Door S","og_description":"You can make your B&D model Controll-A-Door S garage door opener smart. All you need to do is install the ismartgate and wire it to the control board of your existing garage door opener.","og_url":"https:\/\/ismartgate.com\/it\/apriporta-da-garage-intelligente-per-bd-controllare-una-porta-s\/","og_site_name":"ismartgate","article_publisher":"https:\/\/www.facebook.com\/ismartgateofficial\/","og_image":[{"url":"https:\/\/ismartgate.com\/gates.ismartgate-images\/img_77_Controll-A-Door S.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@ismartgate_ww","twitter_misc":{"Tempo di lettura stimato":"21 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ismartgate.com\/smart-garage-door-opener-for-bd-controll-a-door-s\/","url":"https:\/\/ismartgate.com\/smart-garage-door-opener-for-bd-controll-a-door-s\/","name":"Apriporta da garage intelligente per B&amp;D Controll-A-Door S - ismartgate","isPartOf":{"@id":"https:\/\/ismartgate.com\/#website"},"datePublished":"2023-10-22T10:02:29+00:00","description":"\u00c8 possibile rendere intelligente il proprio apriporta di garage B&amp;D modello Controll-A-Door S. \u00c8 sufficiente installare l'ismartgate e collegarlo alla scheda di controllo dell'apriporta del garage esistente.","breadcrumb":{"@id":"https:\/\/ismartgate.com\/smart-garage-door-opener-for-bd-controll-a-door-s\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ismartgate.com\/smart-garage-door-opener-for-bd-controll-a-door-s\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ismartgate.com\/smart-garage-door-opener-for-bd-controll-a-door-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ismartgate.com\/"},{"@type":"ListItem","position":2,"name":"Smart garage door opener for B&#038;D Controll-A-Door S"}]},{"@type":"WebSite","@id":"https:\/\/ismartgate.com\/#website","url":"https:\/\/ismartgate.com\/","name":"ismartgate","description":"Il miglior apriporta per garage intelligente compatibile con Apple HomeKit","publisher":{"@id":"https:\/\/ismartgate.com\/#organization"},"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/ismartgate.com\/#organization","name":"ismartgate","url":"https:\/\/ismartgate.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ismartgate.com\/#\/schema\/logo\/image\/","url":"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ismartgate_header_logo_2x.gif","contentUrl":"https:\/\/ismartgate.com\/wp-content\/uploads\/2018\/07\/ismartgate_header_logo_2x.gif","width":378,"height":56,"caption":"ismartgate"},"image":{"@id":"https:\/\/ismartgate.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ismartgateofficial\/","https:\/\/x.com\/ismartgate_ww","https:\/\/www.youtube.com\/channel\/UCY7edN3zimmxIXJ3tnFMp8A"]}]}},"_links":{"self":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/pages\/38979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/comments?post=38979"}],"version-history":[{"count":0,"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/pages\/38979\/revisions"}],"wp:attachment":[{"href":"https:\/\/ismartgate.com\/it\/wp-json\/wp\/v2\/media?parent=38979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}